{"id":31935,"date":"2024-11-08T21:19:39","date_gmt":"2024-11-08T20:19:39","guid":{"rendered":"https:\/\/www.polen.travel\/sv\/?p=31935"},"modified":"2025-01-22T10:21:56","modified_gmt":"2025-01-22T09:21:56","slug":"nationalparken-wielkopolski","status":"publish","type":"post","link":"https:\/\/www.polen.travel\/sv\/nationalparken-wielkopolski\/","title":{"rendered":"Nationalparken Wielkopolski"},"content":{"rendered":"\n<div class=\"wp-block-group is-style-container\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<!-- empty -->\n\n\n<div class=\"metrics\">\n  <div class=\"metrics__text\">\n    <h1 class=\"is-style-heading-38 mb20 large-mb30\">Nationalparken Wielkopolski<\/h1>\n    <p>Parken, som ligger ca 15 km s\u00f6der om Pozna\u0144, skyddar den f\u00f6r Pojezierze Wielkopolskie (Storpolens sj\u00f6landskap) karakteristiska naturen. H\u00e4r f\u00f6rekommer alla glaciala landskapsformer: h\u00f6jder och kullar, glaciala raviner och insj\u00f6ar samt klippblock. St\u00f6rre delen av parken t\u00e4cks av tall- och blandskog. H\u00e4r p\u00e5tr\u00e4ffas m\u00e5nga s\u00e4llsynta och fridlysta v\u00e4xtarter. I skogen lever bl.a. kronhjort, r\u00e5djur, vildsvin, m\u00e5rd, hare samt talrika f\u00e5gelarter.<\/p>\n  <\/div>\n  <div class=\"metrics__sidebar\">\n    <div class=\"metrics-box\">\n              <div class=\"metrics-box__title\">Grundl\u00e4ggande information<\/div>\n        <div class=\"metrics-box__values\">\n                                        <div class=\"metrics-box__item\">\n      <div class=\"metrics-box__label\">Yta<\/div>\n      <div class=\"metrics-box__value\">7584,93 ha<\/div>\n    <\/div>\n                                <div class=\"metrics-box__item\">\n      <div class=\"metrics-box__label\">Etablerades<\/div>\n      <div class=\"metrics-box__value\">16.04.1957<\/div>\n    <\/div>\n                                <div class=\"metrics-box__item\">\n      <div class=\"metrics-box__label\">Parksymbol<\/div>\n      <div class=\"metrics-box__value\">Kattuggla<\/div>\n    <\/div>\n                                <\/div>\n                    <div class=\"metrics-box__links\">\n                      <a href=\"https:\/\/zpppn.pl\/wielkopolska-national-park-en\/park\" class=\"metrics-box__link external\"\n                                  target=\"_blank\" rel=\"nofollow noopener noreferrer\"\n                            >www<\/a>\n                  <\/div>\n          <\/div>\n  <\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-spacer-small\"><\/div>\n\n\n\n<div class=\"wp-block-group is-style-container\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">  <div class=\"gallery-tiles gallery-tiles--rows-2-3 lightgallery\">\r\n          <a href=\"https:\/\/www.polen.travel\/sv\/wp-content\/uploads\/sites\/22\/2022\/12\/WielkopolskiPN_ok.jpg\" class=\"gallery-tiles__item\" data-src=\"https:\/\/www.polen.travel\/sv\/wp-content\/uploads\/sites\/22\/2022\/12\/WielkopolskiPN_ok.jpg\"\r\n        aria-label=\"Otw\u00f3rz powi\u0119kszone zdj\u0119cie: WielkopolskiPN_ok\">\r\n        <img loading=\"lazy\" decoding=\"async\" width=\"1170\" height=\"780\" src=\"https:\/\/www.polen.travel\/sv\/wp-content\/uploads\/sites\/22\/2022\/12\/WielkopolskiPN_ok.jpg\" class=\"gallery-tiles__thumb\" alt=\"\" srcset=\"https:\/\/www.polen.travel\/sv\/wp-content\/uploads\/sites\/22\/2022\/12\/WielkopolskiPN_ok.jpg 1170w, https:\/\/www.polen.travel\/sv\/wp-content\/uploads\/sites\/22\/2022\/12\/WielkopolskiPN_ok-600x400.jpg 600w, https:\/\/www.polen.travel\/sv\/wp-content\/uploads\/sites\/22\/2022\/12\/WielkopolskiPN_ok-768x512.jpg 768w\" sizes=\"auto, (max-width: 1170px) 100vw, 1170px\" \/>      <\/a>\r\n          <a href=\"https:\/\/www.polen.travel\/sv\/wp-content\/uploads\/sites\/22\/2023\/02\/IMG_2406-Wlkp-Park-Narodowy_Wielkopolskie.jpg\" class=\"gallery-tiles__item\" data-src=\"https:\/\/www.polen.travel\/sv\/wp-content\/uploads\/sites\/22\/2023\/02\/IMG_2406-Wlkp-Park-Narodowy_Wielkopolskie.jpg\"\r\n        aria-label=\"Otw\u00f3rz powi\u0119kszone zdj\u0119cie: IMG_2406 Wlkp Park Narodowy_Wielkopolskie\">\r\n        <img loading=\"lazy\" decoding=\"async\" width=\"1170\" height=\"780\" src=\"https:\/\/www.polen.travel\/sv\/wp-content\/uploads\/sites\/22\/2023\/02\/IMG_2406-Wlkp-Park-Narodowy_Wielkopolskie.jpg\" class=\"gallery-tiles__thumb\" alt=\"\" srcset=\"https:\/\/www.polen.travel\/sv\/wp-content\/uploads\/sites\/22\/2023\/02\/IMG_2406-Wlkp-Park-Narodowy_Wielkopolskie.jpg 1170w, https:\/\/www.polen.travel\/sv\/wp-content\/uploads\/sites\/22\/2023\/02\/IMG_2406-Wlkp-Park-Narodowy_Wielkopolskie-600x400.jpg 600w, https:\/\/www.polen.travel\/sv\/wp-content\/uploads\/sites\/22\/2023\/02\/IMG_2406-Wlkp-Park-Narodowy_Wielkopolskie-768x512.jpg 768w\" sizes=\"auto, (max-width: 1170px) 100vw, 1170px\" \/>      <\/a>\r\n      <\/div>\r\n<\/div><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-spacer-small\"><\/div>\n\n\n\n<div class=\"wp-block-group has-background\" style=\"background-color:#eeeeee\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-spacer-small\"><\/div>\n\n\n\n<div class=\"wp-block-group is-style-container\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h3 class=\"wp-block-heading\">Uppt\u00e4ck platser:<\/h3>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-spacer-small\"><\/div>\n\n\n<div class=\"overflow\">\n  <div class=\"post-slider swiper post-slider--small\" data-schema=\"small\">\n\n    <div class=\"swiper-wrapper\">\n              <div class=\"swiper-slide post-slide\">\n                      <a href=\"https:\/\/www.polen.travel\/sv\/nationalparken-slowinski\/\" class=\"post-box post-box--small\" style=\" background-image: url(https:\/\/www.polen.travel\/sv\/wp-content\/uploads\/sites\/22\/2023\/02\/Slowinski-Parc-National-2-600x388.jpg);\">\n          <div class=\"post-box__hover\" style=\"background-image: url(https:\/\/www.polen.travel\/sv\/wp-content\/uploads\/sites\/22\/2022\/12\/slowinski_pn_540-2.jpg);\"><\/div>\n        <div class=\"post-box__info\">\n            <div class=\"post-box__title\">Nationalparken S\u0142owi\u0144ski<\/div>\n      <div class=\"post-box__more\">Se mer<\/div>\n    <\/div>\n  <\/a>\n\n          <\/div>\n              <div class=\"swiper-slide post-slide\">\n                      <a href=\"https:\/\/www.polen.travel\/sv\/nationalparken-bieszczadzki\/\" class=\"post-box post-box--small\" style=\" background-image: url(https:\/\/www.polen.travel\/sv\/wp-content\/uploads\/sites\/22\/2023\/07\/rys_1170-600x400.jpg);\">\n          <div class=\"post-box__hover\" style=\"background-image: url(https:\/\/www.polen.travel\/sv\/wp-content\/uploads\/sites\/22\/2023\/07\/rys201-600x336.jpg);\"><\/div>\n        <div class=\"post-box__info\">\n            <div class=\"post-box__title\">Nationalparken Bieszczadzki<\/div>\n      <div class=\"post-box__more\">Se mer<\/div>\n    <\/div>\n  <\/a>\n\n          <\/div>\n              <div class=\"swiper-slide post-slide\">\n                      <a href=\"https:\/\/www.polen.travel\/sv\/nationalparken-babiogorski\/\" class=\"post-box post-box--small\" style=\" background-image: url(https:\/\/www.polen.travel\/sv\/wp-content\/uploads\/sites\/22\/2023\/02\/Babia-Gora-National-Park-photo-Marcin-Trybala-600x400.jpg);\">\n          <div class=\"post-box__hover\" style=\"background-image: url(https:\/\/www.polen.travel\/sv\/wp-content\/uploads\/sites\/22\/2023\/02\/eve_1583316509_1-autor-foto-rafal-solinski-male-600x400.jpg);\"><\/div>\n        <div class=\"post-box__info\">\n            <div class=\"post-box__title\">Nationalparken Babiog\u00f3rski<\/div>\n      <div class=\"post-box__more\">Se mer<\/div>\n    <\/div>\n  <\/a>\n\n          <\/div>\n              <div class=\"swiper-slide post-slide\">\n                      <a href=\"https:\/\/www.polen.travel\/sv\/nationalparken-wolinski\/\" class=\"post-box post-box--small\" style=\" background-image: url(https:\/\/www.polen.travel\/sv\/wp-content\/uploads\/sites\/22\/2023\/03\/Fotolia_119430960_Klify-Wolin-600x400.jpg);\">\n          <div class=\"post-box__hover\" style=\"background-image: url(https:\/\/www.polen.travel\/sv\/wp-content\/uploads\/sites\/22\/2023\/02\/Wolinski_Park-600x450.jpeg);\"><\/div>\n        <div class=\"post-box__info\">\n            <div class=\"post-box__title\">Nationalparken Woli\u0144ski<\/div>\n      <div class=\"post-box__more\">Se mer<\/div>\n    <\/div>\n  <\/a>\n\n          <\/div>\n              <div class=\"swiper-slide post-slide\">\n                      <a href=\"https:\/\/www.polen.travel\/sv\/nationalparken-pieninski\/\" class=\"post-box post-box--small\" style=\" background-image: url(https:\/\/www.polen.travel\/sv\/wp-content\/uploads\/sites\/22\/2022\/12\/PIENINY_PN-1-600x401.jpg);\">\n          <div class=\"post-box__hover\" style=\"background-image: url(https:\/\/www.polen.travel\/sv\/wp-content\/uploads\/sites\/22\/2023\/07\/dunajec_splyw_kajaki_1170-600x400.jpg);\"><\/div>\n        <div class=\"post-box__info\">\n            <div class=\"post-box__title\">Nationalparken Pieni\u0144ski<\/div>\n      <div class=\"post-box__more\">Se mer<\/div>\n    <\/div>\n  <\/a>\n\n          <\/div>\n              <div class=\"swiper-slide post-slide\">\n                      <a href=\"https:\/\/www.polen.travel\/sv\/nationalparken-swietokrzyski\/\" class=\"post-box post-box--small\" style=\" background-image: url(https:\/\/www.polen.travel\/sv\/wp-content\/uploads\/sites\/22\/2023\/02\/392_Gory-Swietokrzyskie-i-Swiety-Krzyz-szklany-dom-Zeromskiego_MC_P-600x400.jpg);\">\n          <div class=\"post-box__hover\" style=\"background-image: url(https:\/\/www.polen.travel\/sv\/wp-content\/uploads\/sites\/22\/2023\/02\/3_zamek-Krzyztopor_MC_P-600x400.jpg);\"><\/div>\n        <div class=\"post-box__info\">\n            <div class=\"post-box__title\">Nationalparken \u015awi\u0119tokrzyski<\/div>\n      <div class=\"post-box__more\">Se mer<\/div>\n    <\/div>\n  <\/a>\n\n          <\/div>\n              <div class=\"swiper-slide post-slide\">\n                      <a href=\"https:\/\/www.polen.travel\/sv\/nationalparken-roztoczanski\/\" class=\"post-box post-box--small\" style=\" background-image: url(https:\/\/www.polen.travel\/sv\/wp-content\/uploads\/sites\/22\/2023\/02\/Roztoczanski-PN_stawy-echo-600x400.jpg);\">\n          <div class=\"post-box__hover\" style=\"background-image: url(https:\/\/www.polen.travel\/sv\/wp-content\/uploads\/sites\/22\/2023\/07\/roztocze_1170-600x400.jpg);\"><\/div>\n        <div class=\"post-box__info\">\n            <div class=\"post-box__title\">Nationalparken Roztocza\u0144ski<\/div>\n      <div class=\"post-box__more\">Se mer<\/div>\n    <\/div>\n  <\/a>\n\n          <\/div>\n              <div class=\"swiper-slide post-slide\">\n                      <a href=\"https:\/\/www.polen.travel\/sv\/nationalparken-poleski\/\" class=\"post-box post-box--small\" style=\" background-image: url(https:\/\/www.polen.travel\/sv\/wp-content\/uploads\/sites\/22\/2023\/02\/Poleski-Park-Narodowy2-600x450.jpg);\">\n          <div class=\"post-box__hover\" style=\"background-image: url(https:\/\/www.polen.travel\/sv\/wp-content\/uploads\/sites\/22\/2023\/03\/poleski_park2-600x400.jpg);\"><\/div>\n        <div class=\"post-box__info\">\n            <div class=\"post-box__title\">Nationalparken Poleski<\/div>\n      <div class=\"post-box__more\">Se mer<\/div>\n    <\/div>\n  <\/a>\n\n          <\/div>\n              <div class=\"swiper-slide post-slide\">\n                      <a href=\"https:\/\/www.polen.travel\/sv\/nationalparken-ojcowski\/\" class=\"post-box post-box--small\" style=\" background-image: url(https:\/\/www.polen.travel\/sv\/wp-content\/uploads\/sites\/22\/2023\/02\/255_Ojcowski-Park-Narodowy-i-Zamek-w-Pieskowej-Skale_MC_P-400x600.jpg);\">\n          <div class=\"post-box__hover\" style=\"background-image: url(https:\/\/www.polen.travel\/sv\/wp-content\/uploads\/sites\/22\/2023\/02\/Ojcowski_PN_1170-600x397.jpg);\"><\/div>\n        <div class=\"post-box__info\">\n            <div class=\"post-box__title\">Nationalparken Ojcowski<\/div>\n      <div class=\"post-box__more\">Se mer<\/div>\n    <\/div>\n  <\/a>\n\n          <\/div>\n              <div class=\"swiper-slide post-slide\">\n                      <a href=\"https:\/\/www.polen.travel\/sv\/nationalparken-magurski\/\" class=\"post-box post-box--small\" style=\" background-image: url(https:\/\/www.polen.travel\/sv\/wp-content\/uploads\/sites\/22\/2023\/03\/Magurski_Park_Narodowy-600x400.jpg);\">\n          <div class=\"post-box__hover\" style=\"background-image: url(https:\/\/www.polen.travel\/sv\/wp-content\/uploads\/sites\/22\/2022\/12\/magurski_pn_540.jpg);\"><\/div>\n        <div class=\"post-box__info\">\n            <div class=\"post-box__title\">Nationalparken Magurski<\/div>\n      <div class=\"post-box__more\">Se mer<\/div>\n    <\/div>\n  <\/a>\n\n          <\/div>\n              <div class=\"swiper-slide post-slide\">\n                      <a href=\"https:\/\/www.polen.travel\/sv\/nationalparken-kampinoski\/\" class=\"post-box post-box--small\" style=\" background-image: url(https:\/\/www.polen.travel\/sv\/wp-content\/uploads\/sites\/22\/2023\/07\/kampinoski_pn_slonce_w_lesie_1170-1-600x400.jpg);\">\n          <div class=\"post-box__hover\" style=\"background-image: url(https:\/\/www.polen.travel\/sv\/wp-content\/uploads\/sites\/22\/2023\/07\/Kampinos-forest-600x400.jpg);\"><\/div>\n        <div class=\"post-box__info\">\n            <div class=\"post-box__title\">Nationalparken Kampinoski<\/div>\n      <div class=\"post-box__more\">Se mer<\/div>\n    <\/div>\n  <\/a>\n\n          <\/div>\n              <div class=\"swiper-slide post-slide\">\n                      <a href=\"https:\/\/www.polen.travel\/sv\/nationalparken-wielkopolski\/\" class=\"post-box post-box--small\" style=\" background-image: url(https:\/\/www.polen.travel\/sv\/wp-content\/uploads\/sites\/22\/2022\/12\/wielkopolski_pn_540.jpg);\">\n          <div class=\"post-box__hover\" style=\"background-image: url(https:\/\/www.polen.travel\/sv\/wp-content\/uploads\/sites\/22\/2023\/02\/IMG_2406-Wlkp-Park-Narodowy_Wielkopolskie-600x400.jpg);\"><\/div>\n        <div class=\"post-box__info\">\n            <div class=\"post-box__title\">Nationalparken Wielkopolski<\/div>\n      <div class=\"post-box__more\">Se mer<\/div>\n    <\/div>\n  <\/a>\n\n          <\/div>\n              <div class=\"swiper-slide post-slide\">\n                      <a href=\"https:\/\/www.polen.travel\/sv\/nationalparken-gorczanski\/\" class=\"post-box post-box--small\" style=\" background-image: url(https:\/\/www.polen.travel\/sv\/wp-content\/uploads\/sites\/22\/2023\/02\/Gorce-04142018_0W1A1842-600x400.jpg);\">\n          <div class=\"post-box__hover\" style=\"background-image: url(https:\/\/www.polen.travel\/sv\/wp-content\/uploads\/sites\/22\/2023\/02\/Gorce-04142018_0W1A1842-600x400.jpg);\"><\/div>\n        <div class=\"post-box__info\">\n            <div class=\"post-box__title\">Nationalparken Gorczanski<\/div>\n      <div class=\"post-box__more\">Se mer<\/div>\n    <\/div>\n  <\/a>\n\n          <\/div>\n              <div class=\"swiper-slide post-slide\">\n                      <a href=\"https:\/\/www.polen.travel\/sv\/nationalparken-bory-tucholskie\/\" class=\"post-box post-box--small\" style=\" background-image: url(https:\/\/www.polen.travel\/sv\/wp-content\/uploads\/sites\/22\/2022\/12\/pn_bory_tucholskie_540-1.jpg);\">\n          <div class=\"post-box__hover\" style=\"background-image: url(https:\/\/www.polen.travel\/sv\/wp-content\/uploads\/sites\/22\/2023\/03\/9_Fotolia_EDEN_Bory_Tucholskie_HR-xl-600x400.jpg);\"><\/div>\n        <div class=\"post-box__info\">\n            <div class=\"post-box__title\">Nationalparken Bory Tucholskie<\/div>\n      <div class=\"post-box__more\">Se mer<\/div>\n    <\/div>\n  <\/a>\n\n          <\/div>\n              <div class=\"swiper-slide post-slide\">\n                      <a href=\"https:\/\/www.polen.travel\/sv\/nationalparken-drawienski\/\" class=\"post-box post-box--small\" style=\" background-image: url(https:\/\/www.polen.travel\/sv\/wp-content\/uploads\/sites\/22\/2022\/12\/drawienski_pn_2_540.jpg);\">\n          <div class=\"post-box__hover\" style=\"background-image: url(https:\/\/www.polen.travel\/sv\/wp-content\/uploads\/sites\/22\/2022\/12\/drawienski_pn_540-1.jpg);\"><\/div>\n        <div class=\"post-box__info\">\n            <div class=\"post-box__title\">Nationalparken Drawie\u0144ski<\/div>\n      <div class=\"post-box__more\">Se mer<\/div>\n    <\/div>\n  <\/a>\n\n          <\/div>\n              <div class=\"swiper-slide post-slide\">\n                      <a href=\"https:\/\/www.polen.travel\/sv\/nationalparken-wigierski\/\" class=\"post-box post-box--small\" style=\" background-image: url(https:\/\/www.polen.travel\/sv\/wp-content\/uploads\/sites\/22\/2022\/12\/wigierski_pn_klasztor_1170-600x400.jpg);\">\n          <div class=\"post-box__hover\" style=\"background-image: url(https:\/\/www.polen.travel\/sv\/wp-content\/uploads\/sites\/22\/2022\/12\/jezioro_wigry_540-1.jpg);\"><\/div>\n        <div class=\"post-box__info\">\n            <div class=\"post-box__title\">Nationalparken Wigierski<\/div>\n      <div class=\"post-box__more\">Se mer<\/div>\n    <\/div>\n  <\/a>\n\n          <\/div>\n          <\/div>\n    <div class=\"post-slider__pagination\"><\/div>\n  <\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-spacer-small\"><\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Uppt\u00e4ck platser:<\/p>\n","protected":false},"author":1,"featured_media":7295,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1040],"tags":[1183,1238,1240,1194],"class_list":["post-31935","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nationalparker","tag-sv","tag-natur","tag-nationalparker","tag-vi-rekommenderar"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nationalparken Wielkopolski - Polen Travel (SV)<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.polen.travel\/sv\/nationalparken-wielkopolski\/\" \/>\n<meta property=\"og:locale\" content=\"sv_SE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nationalparken Wielkopolski - Polen Travel (SV)\" \/>\n<meta property=\"og:description\" content=\"Uppt\u00e4ck platser:\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.polen.travel\/sv\/nationalparken-wielkopolski\/\" \/>\n<meta property=\"og:site_name\" content=\"Polen Travel (SV)\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-08T20:19:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-22T09:21:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wp-sv.poland.travel\/wp-content\/uploads\/sites\/22\/2022\/12\/WielkopolskiPN_ok.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"780\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Skriven av\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Ber\u00e4knad l\u00e4stid\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.polen.travel\\\/sv\\\/nationalparken-wielkopolski\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.polen.travel\\\/sv\\\/nationalparken-wielkopolski\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Nationalparken Wielkopolski\",\"datePublished\":\"2024-11-08T20:19:39+00:00\",\"dateModified\":\"2025-01-22T09:21:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.polen.travel\\\/sv\\\/nationalparken-wielkopolski\\\/\"},\"wordCount\":5,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.polen.travel\\\/sv\\\/nationalparken-wielkopolski\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.polen.travel\\\/sv\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2022\\\/12\\\/WielkopolskiPN_ok.jpg\",\"keywords\":[\"sv\",\"naturen\",\"nationalparker\",\"vi-rekommenderar\"],\"articleSection\":[\"Nationalparker\"],\"inLanguage\":\"sv-SE\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.polen.travel\\\/sv\\\/nationalparken-wielkopolski\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.polen.travel\\\/sv\\\/nationalparken-wielkopolski\\\/\",\"url\":\"https:\\\/\\\/www.polen.travel\\\/sv\\\/nationalparken-wielkopolski\\\/\",\"name\":\"Nationalparken Wielkopolski - Polen Travel (SV)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wp-sv.poland.travel\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.polen.travel\\\/sv\\\/nationalparken-wielkopolski\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.polen.travel\\\/sv\\\/nationalparken-wielkopolski\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.polen.travel\\\/sv\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2022\\\/12\\\/WielkopolskiPN_ok.jpg\",\"datePublished\":\"2024-11-08T20:19:39+00:00\",\"dateModified\":\"2025-01-22T09:21:56+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.polen.travel\\\/sv\\\/nationalparken-wielkopolski\\\/#breadcrumb\"},\"inLanguage\":\"sv-SE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.polen.travel\\\/sv\\\/nationalparken-wielkopolski\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"sv-SE\",\"@id\":\"https:\\\/\\\/www.polen.travel\\\/sv\\\/nationalparken-wielkopolski\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.polen.travel\\\/sv\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2022\\\/12\\\/WielkopolskiPN_ok.jpg\",\"contentUrl\":\"https:\\\/\\\/www.polen.travel\\\/sv\\\/wp-content\\\/uploads\\\/sites\\\/22\\\/2022\\\/12\\\/WielkopolskiPN_ok.jpg\",\"width\":1170,\"height\":780},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.polen.travel\\\/sv\\\/nationalparken-wielkopolski\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home page\",\"item\":\"https:\\\/\\\/www.polen.travel\\\/sv\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uppt\u00e4ck Polen\",\"item\":\"https:\\\/\\\/www.polen.travel\\\/sv\\\/upptack-polen\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Nationalparker\",\"item\":\"https:\\\/\\\/www.polen.travel\\\/sv\\\/nationalparker\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Nationalparken Wielkopolski\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wp-sv.poland.travel\\\/#website\",\"url\":\"https:\\\/\\\/wp-sv.poland.travel\\\/\",\"name\":\"Polen Travel\",\"description\":\"...\",\"alternateName\":\"Polen.travel \u2013 Officiell turistguide till Polen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wp-sv.poland.travel\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"sv-SE\"},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\\\/\\\/www.polen.travel\\\/sv\\\/author\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nationalparken Wielkopolski - Polen Travel (SV)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.polen.travel\/sv\/nationalparken-wielkopolski\/","og_locale":"sv_SE","og_type":"article","og_title":"Nationalparken Wielkopolski - Polen Travel (SV)","og_description":"Uppt\u00e4ck platser:","og_url":"https:\/\/www.polen.travel\/sv\/nationalparken-wielkopolski\/","og_site_name":"Polen Travel (SV)","article_published_time":"2024-11-08T20:19:39+00:00","article_modified_time":"2025-01-22T09:21:56+00:00","og_image":[{"width":1170,"height":780,"url":"https:\/\/wp-sv.poland.travel\/wp-content\/uploads\/sites\/22\/2022\/12\/WielkopolskiPN_ok.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Skriven av":"","Ber\u00e4knad l\u00e4stid":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.polen.travel\/sv\/nationalparken-wielkopolski\/#article","isPartOf":{"@id":"https:\/\/www.polen.travel\/sv\/nationalparken-wielkopolski\/"},"author":{"name":"","@id":""},"headline":"Nationalparken Wielkopolski","datePublished":"2024-11-08T20:19:39+00:00","dateModified":"2025-01-22T09:21:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.polen.travel\/sv\/nationalparken-wielkopolski\/"},"wordCount":5,"commentCount":0,"image":{"@id":"https:\/\/www.polen.travel\/sv\/nationalparken-wielkopolski\/#primaryimage"},"thumbnailUrl":"https:\/\/www.polen.travel\/sv\/wp-content\/uploads\/sites\/22\/2022\/12\/WielkopolskiPN_ok.jpg","keywords":["sv","naturen","nationalparker","vi-rekommenderar"],"articleSection":["Nationalparker"],"inLanguage":"sv-SE","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.polen.travel\/sv\/nationalparken-wielkopolski\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.polen.travel\/sv\/nationalparken-wielkopolski\/","url":"https:\/\/www.polen.travel\/sv\/nationalparken-wielkopolski\/","name":"Nationalparken Wielkopolski - Polen Travel (SV)","isPartOf":{"@id":"https:\/\/wp-sv.poland.travel\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.polen.travel\/sv\/nationalparken-wielkopolski\/#primaryimage"},"image":{"@id":"https:\/\/www.polen.travel\/sv\/nationalparken-wielkopolski\/#primaryimage"},"thumbnailUrl":"https:\/\/www.polen.travel\/sv\/wp-content\/uploads\/sites\/22\/2022\/12\/WielkopolskiPN_ok.jpg","datePublished":"2024-11-08T20:19:39+00:00","dateModified":"2025-01-22T09:21:56+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/www.polen.travel\/sv\/nationalparken-wielkopolski\/#breadcrumb"},"inLanguage":"sv-SE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.polen.travel\/sv\/nationalparken-wielkopolski\/"]}]},{"@type":"ImageObject","inLanguage":"sv-SE","@id":"https:\/\/www.polen.travel\/sv\/nationalparken-wielkopolski\/#primaryimage","url":"https:\/\/www.polen.travel\/sv\/wp-content\/uploads\/sites\/22\/2022\/12\/WielkopolskiPN_ok.jpg","contentUrl":"https:\/\/www.polen.travel\/sv\/wp-content\/uploads\/sites\/22\/2022\/12\/WielkopolskiPN_ok.jpg","width":1170,"height":780},{"@type":"BreadcrumbList","@id":"https:\/\/www.polen.travel\/sv\/nationalparken-wielkopolski\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home page","item":"https:\/\/www.polen.travel\/sv\/"},{"@type":"ListItem","position":2,"name":"Uppt\u00e4ck Polen","item":"https:\/\/www.polen.travel\/sv\/upptack-polen\/"},{"@type":"ListItem","position":3,"name":"Nationalparker","item":"https:\/\/www.polen.travel\/sv\/nationalparker\/"},{"@type":"ListItem","position":4,"name":"Nationalparken Wielkopolski"}]},{"@type":"WebSite","@id":"https:\/\/wp-sv.poland.travel\/#website","url":"https:\/\/wp-sv.poland.travel\/","name":"Polen Travel","description":"...","alternateName":"Polen.travel \u2013 Officiell turistguide till Polen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wp-sv.poland.travel\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"sv-SE"},{"@type":"Person","@id":"","url":"https:\/\/www.polen.travel\/sv\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/www.polen.travel\/sv\/wp-json\/wp\/v2\/posts\/31935","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.polen.travel\/sv\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.polen.travel\/sv\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.polen.travel\/sv\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.polen.travel\/sv\/wp-json\/wp\/v2\/comments?post=31935"}],"version-history":[{"count":7,"href":"https:\/\/www.polen.travel\/sv\/wp-json\/wp\/v2\/posts\/31935\/revisions"}],"predecessor-version":[{"id":37877,"href":"https:\/\/www.polen.travel\/sv\/wp-json\/wp\/v2\/posts\/31935\/revisions\/37877"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.polen.travel\/sv\/wp-json\/wp\/v2\/media\/7295"}],"wp:attachment":[{"href":"https:\/\/www.polen.travel\/sv\/wp-json\/wp\/v2\/media?parent=31935"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.polen.travel\/sv\/wp-json\/wp\/v2\/categories?post=31935"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.polen.travel\/sv\/wp-json\/wp\/v2\/tags?post=31935"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}