{"id":32110,"date":"2025-03-02T14:10:51","date_gmt":"2025-03-02T13:10:51","guid":{"rendered":"https:\/\/www.polen.travel\/dk\/?p=32110"},"modified":"2025-03-02T14:10:52","modified_gmt":"2025-03-02T13:10:52","slug":"regionen-lubelskie","status":"publish","type":"post","link":"https:\/\/www.polen.travel\/dk\/regionen-lubelskie\/","title":{"rendered":"Regionen Lubelskie"},"content":{"rendered":"\n<div class=\"wp-block-group is-style-container\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<!-- empty -->\n\n\n<div class=\"metrics\">\n  <div class=\"metrics__text\">\n    <h1 class=\"is-style-heading-38 mb20 large-mb30\">Regionen Lubelskie \u2013 Bug flodens rute<\/h1>\n    <p><strong>Den tredjest\u00f8rste region i Polen ligger langs landets \u00f8stlige gr\u00e6nse. Dets naboer er Hviderusland og Ukraine, p\u00e5 den anden side af Bug, en vild og bugtet flod. Det er det omr\u00e5de, hvor polsk, russisk, katolsk, ortodoks og j\u00f8disk indflydelse er blandet sammen. Det er et omr\u00e5de, som har oplevet mange forandringer. Et fuldblods gr\u00e6nseland.<\/strong><\/p>\n  <\/div>\n  <div class=\"metrics__sidebar\">\n    <div class=\"metrics-box\">\n              <div class=\"metrics-box__title\">Grundl\u00e6ggende information<\/div>\n        <div class=\"metrics-box__values\">\n                                        <div class=\"metrics-box__item\">\n      <div class=\"metrics-box__label\">Befolkning<\/div>\n      <div class=\"metrics-box__value\">2 038 299 (2017)<\/div>\n    <\/div>\n                                <div class=\"metrics-box__item\">\n      <div class=\"metrics-box__label\">Omr\u00e5de<\/div>\n      <div class=\"metrics-box__value\">25 122 km\u00b2<\/div>\n    <\/div>\n                                <\/div>\n                    <div class=\"metrics-box__links\">\n                      <a href=\"https:\/\/www.lubelskietravel.pl\/en\/\" class=\"metrics-box__link external\"\n                                  target=\"_blank\" rel=\"nofollow noopener noreferrer\"\n                            >www<\/a>\n                  <\/div>\n          <\/div>\n  <\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group is-style-container-medium\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<p>Regionen Lubelskie er f\u00f8destedet for mange j\u00f8diske videnskabsm\u00e6nd, og herfra stammer familierne til nogle af de st\u00f8rste j\u00f8diske forfattere: Izrael Joszua og Isaac Bashevis Singer. Holocaust fandt ogs\u00e5 sted her, og i dag er de tidligere tyske koncentrationslejre i Majdanek og Sobibor blevet til museer, som en p\u00e5mindelse om den forf\u00e6rdelige tid.<\/p>\n\n\n\n<p>Regionshovedstaden Lublin er den st\u00f8rste by i det \u00f8stlige Polen. Den er et pulserende, akademisk center (12 universiteter), og her blev en historisk traktat underskrevet. P\u00e5 slottet findes en af de st\u00f8rste europ\u00e6iske skatte, Sankt Trinitary-Kapellet med en gotisk hv\u00e6lving, prydet med unikke byzantinske Rus-Kalkmalerier.<\/p>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-spacer-small\"><\/div>\n\n\n\n<div class=\"wp-block-group is-style-container\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">  <div class=\"gallery-tiles gallery-tiles--rows-2-3 lightgallery\">\r\n          <a href=\"https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/07\/17140_Lublin_Zamek_KK_HR.jpg\" class=\"gallery-tiles__item\" data-src=\"https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/07\/17140_Lublin_Zamek_KK_HR.jpg\"\r\n        aria-label=\"Otw\u00f3rz powi\u0119kszone zdj\u0119cie: 17140_Lublin_Zamek_KK_HR\">\r\n        <img loading=\"lazy\" decoding=\"async\" width=\"1180\" height=\"780\" src=\"https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/07\/17140_Lublin_Zamek_KK_HR.jpg\" class=\"gallery-tiles__thumb\" alt=\"\" srcset=\"https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/07\/17140_Lublin_Zamek_KK_HR.jpg 1180w, https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/07\/17140_Lublin_Zamek_KK_HR-600x397.jpg 600w, https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/07\/17140_Lublin_Zamek_KK_HR-768x508.jpg 768w\" sizes=\"auto, (max-width: 1180px) 100vw, 1180px\" \/>      <\/a>\r\n          <a href=\"https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/03\/Chelmno-gotycko-renesansowy-ratusz-scaled.jpg\" class=\"gallery-tiles__item\" data-src=\"https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/03\/Chelmno-gotycko-renesansowy-ratusz-scaled.jpg\"\r\n        aria-label=\"Otw\u00f3rz powi\u0119kszone zdj\u0119cie: Che\u0142mno-gotycko-renesansowy ratusz\">\r\n        <img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"773\" src=\"https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/03\/Chelmno-gotycko-renesansowy-ratusz-1200x773.jpg\" class=\"gallery-tiles__thumb\" alt=\"\" srcset=\"https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/03\/Chelmno-gotycko-renesansowy-ratusz-1200x773.jpg 1200w, https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/03\/Chelmno-gotycko-renesansowy-ratusz-600x386.jpg 600w, https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/03\/Chelmno-gotycko-renesansowy-ratusz-768x495.jpg 768w, https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/03\/Chelmno-gotycko-renesansowy-ratusz-1536x989.jpg 1536w, https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/03\/Chelmno-gotycko-renesansowy-ratusz-2048x1319.jpg 2048w, https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/03\/Chelmno-gotycko-renesansowy-ratusz-1920x1237.jpg 1920w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/>      <\/a>\r\n          <a href=\"https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2022\/12\/muzeum_wsi_lubelskiej_1170.jpg\" class=\"gallery-tiles__item\" data-src=\"https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2022\/12\/muzeum_wsi_lubelskiej_1170.jpg\"\r\n        aria-label=\"Otw\u00f3rz powi\u0119kszone zdj\u0119cie: muzeum_wsi_lubelskiej_1170\">\r\n        <img loading=\"lazy\" decoding=\"async\" width=\"1170\" height=\"780\" src=\"https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2022\/12\/muzeum_wsi_lubelskiej_1170.jpg\" class=\"gallery-tiles__thumb\" alt=\"\" srcset=\"https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2022\/12\/muzeum_wsi_lubelskiej_1170.jpg 1170w, https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2022\/12\/muzeum_wsi_lubelskiej_1170-600x400.jpg 600w, https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2022\/12\/muzeum_wsi_lubelskiej_1170-768x512.jpg 768w\" sizes=\"auto, (max-width: 1170px) 100vw, 1170px\" \/>      <\/a>\r\n          <a href=\"https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2022\/12\/muzeum_wsi_lubelskiej_1170-1.jpg\" class=\"gallery-tiles__item\" data-src=\"https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2022\/12\/muzeum_wsi_lubelskiej_1170-1.jpg\"\r\n        aria-label=\"Otw\u00f3rz powi\u0119kszone zdj\u0119cie: muzeum_wsi_lubelskiej_1170-1\">\r\n        <img loading=\"lazy\" decoding=\"async\" width=\"1170\" height=\"780\" src=\"https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2022\/12\/muzeum_wsi_lubelskiej_1170-1.jpg\" class=\"gallery-tiles__thumb\" alt=\"\" srcset=\"https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2022\/12\/muzeum_wsi_lubelskiej_1170-1.jpg 1170w, https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2022\/12\/muzeum_wsi_lubelskiej_1170-1-600x400.jpg 600w, https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2022\/12\/muzeum_wsi_lubelskiej_1170-1-768x512.jpg 768w\" sizes=\"auto, (max-width: 1170px) 100vw, 1170px\" \/>      <\/a>\r\n          <a href=\"https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2022\/12\/lublin_dziedziniec_zamku_lubelskiego_donzon_kaplica_trojcy_swietej_1170.jpg\" class=\"gallery-tiles__item\" data-src=\"https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2022\/12\/lublin_dziedziniec_zamku_lubelskiego_donzon_kaplica_trojcy_swietej_1170.jpg\"\r\n        aria-label=\"Otw\u00f3rz powi\u0119kszone zdj\u0119cie: lublin_dziedziniec_zamku_lubelskiego_donzon_kaplica_trojcy_swietej_1170\">\r\n        <img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2022\/12\/lublin_dziedziniec_zamku_lubelskiego_donzon_kaplica_trojcy_swietej_1170-1200x800.jpg\" class=\"gallery-tiles__thumb\" alt=\"\" srcset=\"https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2022\/12\/lublin_dziedziniec_zamku_lubelskiego_donzon_kaplica_trojcy_swietej_1170-1200x800.jpg 1200w, https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2022\/12\/lublin_dziedziniec_zamku_lubelskiego_donzon_kaplica_trojcy_swietej_1170-600x400.jpg 600w, https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2022\/12\/lublin_dziedziniec_zamku_lubelskiego_donzon_kaplica_trojcy_swietej_1170-768x512.jpg 768w, https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2022\/12\/lublin_dziedziniec_zamku_lubelskiego_donzon_kaplica_trojcy_swietej_1170.jpg 1536w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/>      <\/a>\r\n      <\/div>\r\n<\/div><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-spacer-small\"><\/div>\n\n\n\n<div class=\"wp-block-group is-style-container-medium\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<p>En anden af Lubelskies skatte er ren\u00e6ssancebyen Zamosc \u2013 som blev anlagt med Padova i Italien som model. Zamosc er opf\u00f8rt p\u00e5 UNESCO\u2019s liste over verdens kulturarv. Underjordiske tunneler er hugget ud i kalken under de historiske ortodokse og katolske kirker i byen Chelm. De er unikke, ogs\u00e5 p\u00e5 europ\u00e6isk plan.<\/p>\n\n\n\n<p>Et andet sted fyldt med charme er den popul\u00e6re by Kazimierz Dolny ved Wisla og slottet i Kozlowka, en af de smukkeste, adelige residenser i Polen. Du m\u00e5 heller ikke g\u00e5 glip af araberhestestutteriet i Janow Podlaski, hvor Shirley Watts, hustru til trommeslageren i The Rolling Stones, er en af de faste kunder.<\/p>\n\n\n\n<p>De vigtigste naturomr\u00e5der er: Nationalparken Poleski, et stort omr\u00e5de med heder, der minder meget om tundraen og nationalparken Roztoczanski med kalkholdige bakker, dybe dale og vandfald. Her regerer de polske ponyer, efterkommere af tarpaner, i et landskab fyldt med tempererede planter fra Syd\u00f8steuropa.<\/p>\n<\/div><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-spacer-small\"><\/div>\n\n\n\n<div class=\"wp-block-group has-background\" style=\"background-color:#eeeeee\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-spacer-small\"><\/div>\n\n\n\n<div class=\"wp-block-group is-style-container\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h3 class=\"wp-block-heading\">Oplev vores regioner:<\/h3>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-spacer-small\"><\/div>\n\n\n<div class=\"overflow\">\n  <div class=\"post-slider swiper post-slider--small\" data-schema=\"small\">\n\n    <div class=\"swiper-wrapper\">\n              <div class=\"swiper-slide post-slide\">\n                      <a href=\"https:\/\/www.polen.travel\/dk\/regionen-podkarpackie\/\" class=\"post-box post-box--small\" style=\" background-image: url(https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/07\/rys_1170-600x400.jpg);\">\n          <div class=\"post-box__hover\" style=\"background-image: url(https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/07\/centrum_dziedzictwa_szkla_krosno_wyroby_1170-1-600x400.jpg);\"><\/div>\n        <div class=\"post-box__info\">\n            <div class=\"post-box__title\">Regionen Podkarpackie<\/div>\n      <div class=\"post-box__more\">Se mere<\/div>\n    <\/div>\n  <\/a>\n\n          <\/div>\n              <div class=\"swiper-slide post-slide\">\n                      <a href=\"https:\/\/www.polen.travel\/dk\/regionen-malopolskie\/\" class=\"post-box post-box--small\" style=\" background-image: url(https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/07\/tatry_krokusy_1170-600x400.jpg);\">\n          <div class=\"post-box__hover\" style=\"background-image: url(https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/07\/krakow_wawel_w_kwiatach_1170-600x400.jpg);\"><\/div>\n        <div class=\"post-box__info\">\n            <div class=\"post-box__title\">Regionen Ma\u0142opolskie<\/div>\n      <div class=\"post-box__more\">Se mere<\/div>\n    <\/div>\n  <\/a>\n\n          <\/div>\n              <div class=\"swiper-slide post-slide\">\n                      <a href=\"https:\/\/www.polen.travel\/dk\/regionen-swietokrzyskie\/\" class=\"post-box post-box--small\" style=\" background-image: url(https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/02\/392_Gory-Swietokrzyskie-i-Swiety-Krzyz-szklany-dom-Zeromskiego_MC_P-600x400.jpg);\">\n          <div class=\"post-box__hover\" style=\"background-image: url(https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2022\/12\/jaskinia_raj_1170-600x399.jpg);\"><\/div>\n        <div class=\"post-box__info\">\n            <div class=\"post-box__title\">Regionen \u015awi\u0119tokrzyskie<\/div>\n      <div class=\"post-box__more\">Se mere<\/div>\n    <\/div>\n  <\/a>\n\n          <\/div>\n              <div class=\"swiper-slide post-slide\">\n                      <a href=\"https:\/\/www.polen.travel\/dk\/regionen-slaskie\/\" class=\"post-box post-box--small\" style=\" background-image: url(https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2022\/12\/zamek_czocha_1170-600x400.jpg);\">\n          <div class=\"post-box__hover\" style=\"background-image: url(https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/01\/Kopalnia-Guido-Zabrze-6-fot-www.slaskie.travel-OpenGroup.com_.pl_-600x400.jpg);\"><\/div>\n        <div class=\"post-box__info\">\n            <div class=\"post-box__title\">Regionen \u015al\u0105skie<\/div>\n      <div class=\"post-box__more\">Se mere<\/div>\n    <\/div>\n  <\/a>\n\n          <\/div>\n              <div class=\"swiper-slide post-slide\">\n                      <a href=\"https:\/\/www.polen.travel\/dk\/regionen-opolskie\/\" class=\"post-box post-box--small\" style=\" background-image: url(https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2022\/12\/zamek_moszna_odbicie_1170-1-600x400.jpg);\">\n          <div class=\"post-box__hover\" style=\"background-image: url(https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2022\/12\/opole_amfiteatr_1170-2-600x400.jpg);\"><\/div>\n        <div class=\"post-box__info\">\n            <div class=\"post-box__title\">Regionen Opolskie<\/div>\n      <div class=\"post-box__more\">Se mere<\/div>\n    <\/div>\n  <\/a>\n\n          <\/div>\n              <div class=\"swiper-slide post-slide\">\n                      <a href=\"https:\/\/www.polen.travel\/dk\/regionen-lubelskie\/\" class=\"post-box post-box--small\" style=\" background-image: url(https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/02\/Roztoczanski-PN_stawy-echo-600x400.jpg);\">\n          <div class=\"post-box__hover\" style=\"background-image: url(https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/07\/17140_Lublin_Zamek_KK_HR-1-600x397.jpg);\"><\/div>\n        <div class=\"post-box__info\">\n            <div class=\"post-box__title\">Regionen Lubelskie<\/div>\n      <div class=\"post-box__more\">Se mere<\/div>\n    <\/div>\n  <\/a>\n\n          <\/div>\n              <div class=\"swiper-slide post-slide\">\n                      <a href=\"https:\/\/www.polen.travel\/dk\/regionen-mazowieckie\/\" class=\"post-box post-box--small\" style=\" background-image: url(https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/01\/290390197_Zelazowa_Wola_Adobe-600x400.jpg);\">\n          <div class=\"post-box__hover\" style=\"background-image: url(https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/07\/Warszawa_G162918-600x400.jpg);\"><\/div>\n        <div class=\"post-box__info\">\n            <div class=\"post-box__title\">Regionen Mazowieckie<\/div>\n      <div class=\"post-box__more\">Se mere<\/div>\n    <\/div>\n  <\/a>\n\n          <\/div>\n              <div class=\"swiper-slide post-slide\">\n                      <a href=\"https:\/\/www.polen.travel\/dk\/regionen-lodzkie\/\" class=\"post-box post-box--small\" style=\" background-image: url(https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2022\/12\/arkadia_1170-600x400.jpg);\">\n          <div class=\"post-box__hover\" style=\"background-image: url(https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2022\/12\/lodz_manufaktura_1170-600x400.jpg);\"><\/div>\n        <div class=\"post-box__info\">\n            <div class=\"post-box__title\">Regionen \u0141\u00f3dzkie<\/div>\n      <div class=\"post-box__more\">Se mere<\/div>\n    <\/div>\n  <\/a>\n\n          <\/div>\n              <div class=\"swiper-slide post-slide\">\n                      <a href=\"https:\/\/www.polen.travel\/dk\/regionen-dolnoslaskie\/\" class=\"post-box post-box--small\" style=\" background-image: url(https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2022\/12\/sniezka_1170-600x400.jpg);\">\n          <div class=\"post-box__hover\" style=\"background-image: url(https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/07\/WROCLAW_1-600x400.jpg);\"><\/div>\n        <div class=\"post-box__info\">\n            <div class=\"post-box__title\">Regionen Dolno\u015bl\u0105skie<\/div>\n      <div class=\"post-box__more\">Se mere<\/div>\n    <\/div>\n  <\/a>\n\n          <\/div>\n              <div class=\"swiper-slide post-slide\">\n                      <a href=\"https:\/\/www.polen.travel\/dk\/regionen-lubuskie\/\" class=\"post-box post-box--small\" style=\" background-image: url(https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2022\/12\/park_muzakowski_540.jpg);\">\n          <div class=\"post-box__hover\" style=\"background-image: url(https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2022\/12\/gorzow_wlk_katedra_i_bamberka_1170-1-600x400.jpg);\"><\/div>\n        <div class=\"post-box__info\">\n            <div class=\"post-box__title\">Regionen Lubuskie<\/div>\n      <div class=\"post-box__more\">Se mere<\/div>\n    <\/div>\n  <\/a>\n\n          <\/div>\n              <div class=\"swiper-slide post-slide\">\n                      <a href=\"https:\/\/www.polen.travel\/dk\/regionen-wielkopolska\/\" class=\"post-box post-box--small\" style=\" background-image: url(https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2022\/12\/kladka_sliwno-waniewo_npn_1170-600x400.jpg);\">\n          <div class=\"post-box__hover\" style=\"background-image: url(https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/07\/POZNAN_3-600x400.jpg);\"><\/div>\n        <div class=\"post-box__info\">\n            <div class=\"post-box__title\">Regionen Wielkopolska<\/div>\n      <div class=\"post-box__more\">Se mere<\/div>\n    <\/div>\n  <\/a>\n\n          <\/div>\n              <div class=\"swiper-slide post-slide\">\n                      <a href=\"https:\/\/www.polen.travel\/dk\/regionen-kujawsko-pomorskie\/\" class=\"post-box post-box--small\" style=\" background-image: url(https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2022\/12\/pn_bory_tucholskie_540.jpg);\">\n          <div class=\"post-box__hover\" style=\"background-image: url(https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/07\/Bydgoszcz1170-600x400.jpg);\"><\/div>\n        <div class=\"post-box__info\">\n            <div class=\"post-box__title\">Regionen Kujawsko-Pomorskie<\/div>\n      <div class=\"post-box__more\">Se mere<\/div>\n    <\/div>\n  <\/a>\n\n          <\/div>\n              <div class=\"swiper-slide post-slide\">\n                      <a href=\"https:\/\/www.polen.travel\/dk\/regionen-podlaskie\/\" class=\"post-box post-box--small\" style=\" background-image: url(https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2022\/12\/zubry_1170-600x400.jpg);\">\n          <div class=\"post-box__hover\" style=\"background-image: url(https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2022\/12\/grabarka_540.jpg);\"><\/div>\n        <div class=\"post-box__info\">\n            <div class=\"post-box__title\">Regionen Podlaskie<\/div>\n      <div class=\"post-box__more\">Se mere<\/div>\n    <\/div>\n  <\/a>\n\n          <\/div>\n              <div class=\"swiper-slide post-slide\">\n                      <a href=\"https:\/\/www.polen.travel\/dk\/regionen-warminsko-mazurskie\/\" class=\"post-box post-box--small\" style=\" background-image: url(https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/07\/mazury_jezioro_zaglowka_1170-600x400.jpg);\">\n          <div class=\"post-box__hover\" style=\"background-image: url(https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/01\/regiony2-600x400.jpg);\"><\/div>\n        <div class=\"post-box__info\">\n            <div class=\"post-box__title\">Regionen Warmi\u0144sko-Mazurskie<\/div>\n      <div class=\"post-box__more\">Se mere<\/div>\n    <\/div>\n  <\/a>\n\n          <\/div>\n              <div class=\"swiper-slide post-slide\">\n                      <a href=\"https:\/\/www.polen.travel\/dk\/regionen-vestpommern\/\" class=\"post-box post-box--small\" style=\" background-image: url(https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2022\/12\/swinoujscie_540-1.jpg);\">\n          <div class=\"post-box__hover\" style=\"background-image: url(https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2022\/12\/wolinski_pn_540-2.jpg);\"><\/div>\n        <div class=\"post-box__info\">\n            <div class=\"post-box__title\">Regionen Vestpommern<\/div>\n      <div class=\"post-box__more\">Se mere<\/div>\n    <\/div>\n  <\/a>\n\n          <\/div>\n              <div class=\"swiper-slide post-slide\">\n                      <a href=\"https:\/\/www.polen.travel\/dk\/regionen-pommern\/\" class=\"post-box post-box--small\" style=\" background-image: url(https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/07\/Gdanskfull1170-600x400.jpg);\">\n          <div class=\"post-box__hover\" style=\"background-image: url(https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2022\/12\/sopot_plaza_1170-600x399.jpg);\"><\/div>\n        <div class=\"post-box__info\">\n            <div class=\"post-box__title\">Regionen Pommern<\/div>\n      <div class=\"post-box__more\">Se mere<\/div>\n    <\/div>\n  <\/a>\n\n          <\/div>\n          <\/div>\n    <div class=\"post-slider__pagination\"><\/div>\n  <\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-spacer-small\"><\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Regionen Lubelskie er f\u00f8destedet for mange j\u00f8diske videnskabsm\u00e6nd, og herfra stammer familierne til nogle af de st\u00f8rste j\u00f8diske forfattere: Izrael Joszua og Isaac Bashevis Singer. Holocaust fandt ogs\u00e5 sted her, og i dag er de tidligere tyske koncentrationslejre i Majdanek og Sobibor blevet til museer, som en p\u00e5mindelse om den forf\u00e6rdelige tid. Regionshovedstaden Lublin er [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":21110,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1038],"tags":[1205,1208],"class_list":["post-32110","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-regioner","tag-hvad-skal-man-se","tag-regioner"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Regionen Lubelskie - Polen Travel (DK)<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wp-dk.poland.travel\/regionen-lubelskie\/\" \/>\n<meta property=\"og:locale\" content=\"da_DK\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Regionen Lubelskie - Polen Travel (DK)\" \/>\n<meta property=\"og:description\" content=\"Regionen Lubelskie er f\u00f8destedet for mange j\u00f8diske videnskabsm\u00e6nd, og herfra stammer familierne til nogle af de st\u00f8rste j\u00f8diske forfattere: Izrael Joszua og Isaac Bashevis Singer. Holocaust fandt ogs\u00e5 sted her, og i dag er de tidligere tyske koncentrationslejre i Majdanek og Sobibor blevet til museer, som en p\u00e5mindelse om den forf\u00e6rdelige tid. Regionshovedstaden Lublin er [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wp-dk.poland.travel\/regionen-lubelskie\/\" \/>\n<meta property=\"og:site_name\" content=\"Polen Travel (DK)\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-02T13:10:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-02T13:10:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wp-dk.poland.travel\/wp-content\/uploads\/sites\/24\/2023\/02\/Roztoczanski-PN_1920.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"582\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Skrevet af\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimeret l\u00e6setid\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutter\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wp-dk.poland.travel\\\/regionen-lubelskie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wp-dk.poland.travel\\\/regionen-lubelskie\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Regionen Lubelskie\",\"datePublished\":\"2025-03-02T13:10:51+00:00\",\"dateModified\":\"2025-03-02T13:10:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wp-dk.poland.travel\\\/regionen-lubelskie\\\/\"},\"wordCount\":266,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.polen.travel\\\/dk\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/wp-dk.poland.travel\\\/regionen-lubelskie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.polen.travel\\\/dk\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2023\\\/02\\\/Roztoczanski-PN_1920.jpg\",\"keywords\":[\"hvad-skal-man-se\",\"regioner\"],\"articleSection\":[\"Regioner\"],\"inLanguage\":\"da-DK\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/wp-dk.poland.travel\\\/regionen-lubelskie\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wp-dk.poland.travel\\\/regionen-lubelskie\\\/\",\"url\":\"https:\\\/\\\/wp-dk.poland.travel\\\/regionen-lubelskie\\\/\",\"name\":\"Regionen Lubelskie - Polen Travel (DK)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.polen.travel\\\/dk\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wp-dk.poland.travel\\\/regionen-lubelskie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wp-dk.poland.travel\\\/regionen-lubelskie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.polen.travel\\\/dk\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2023\\\/02\\\/Roztoczanski-PN_1920.jpg\",\"datePublished\":\"2025-03-02T13:10:51+00:00\",\"dateModified\":\"2025-03-02T13:10:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wp-dk.poland.travel\\\/regionen-lubelskie\\\/#breadcrumb\"},\"inLanguage\":\"da-DK\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wp-dk.poland.travel\\\/regionen-lubelskie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"da-DK\",\"@id\":\"https:\\\/\\\/wp-dk.poland.travel\\\/regionen-lubelskie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.polen.travel\\\/dk\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2023\\\/02\\\/Roztoczanski-PN_1920.jpg\",\"contentUrl\":\"https:\\\/\\\/www.polen.travel\\\/dk\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2023\\\/02\\\/Roztoczanski-PN_1920.jpg\",\"width\":1920,\"height\":582,\"caption\":\"Horses , Stawy Echo , Roztocze National Park , Poland\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wp-dk.poland.travel\\\/regionen-lubelskie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home page\",\"item\":\"https:\\\/\\\/www.polen.travel\\\/dk\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Oplev Polen\",\"item\":\"https:\\\/\\\/wp-dk.poland.travel\\\/oplev-polen\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Regioner\",\"item\":\"https:\\\/\\\/wp-dk.poland.travel\\\/regioner\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Regionen Lubelskie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.polen.travel\\\/dk\\\/#website\",\"url\":\"https:\\\/\\\/www.polen.travel\\\/dk\\\/\",\"name\":\"Polen Travel (DK)\",\"description\":\"...\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.polen.travel\\\/dk\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.polen.travel\\\/dk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"da-DK\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.polen.travel\\\/dk\\\/#organization\",\"name\":\"Polen Travel (DK)\",\"url\":\"https:\\\/\\\/www.polen.travel\\\/dk\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"da-DK\",\"@id\":\"https:\\\/\\\/www.polen.travel\\\/dk\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/en-en.polska.travel\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2022\\\/11\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/en-en.polska.travel\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2022\\\/11\\\/logo.svg\",\"width\":198,\"height\":96,\"caption\":\"Polen Travel (DK)\"},\"image\":{\"@id\":\"https:\\\/\\\/www.polen.travel\\\/dk\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\\\/\\\/www.polen.travel\\\/dk\\\/author\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Regionen Lubelskie - Polen Travel (DK)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wp-dk.poland.travel\/regionen-lubelskie\/","og_locale":"da_DK","og_type":"article","og_title":"Regionen Lubelskie - Polen Travel (DK)","og_description":"Regionen Lubelskie er f\u00f8destedet for mange j\u00f8diske videnskabsm\u00e6nd, og herfra stammer familierne til nogle af de st\u00f8rste j\u00f8diske forfattere: Izrael Joszua og Isaac Bashevis Singer. Holocaust fandt ogs\u00e5 sted her, og i dag er de tidligere tyske koncentrationslejre i Majdanek og Sobibor blevet til museer, som en p\u00e5mindelse om den forf\u00e6rdelige tid. Regionshovedstaden Lublin er [&hellip;]","og_url":"https:\/\/wp-dk.poland.travel\/regionen-lubelskie\/","og_site_name":"Polen Travel (DK)","article_published_time":"2025-03-02T13:10:51+00:00","article_modified_time":"2025-03-02T13:10:52+00:00","og_image":[{"width":1920,"height":582,"url":"https:\/\/wp-dk.poland.travel\/wp-content\/uploads\/sites\/24\/2023\/02\/Roztoczanski-PN_1920.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Skrevet af":"","Estimeret l\u00e6setid":"2 minutter"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wp-dk.poland.travel\/regionen-lubelskie\/#article","isPartOf":{"@id":"https:\/\/wp-dk.poland.travel\/regionen-lubelskie\/"},"author":{"name":"","@id":""},"headline":"Regionen Lubelskie","datePublished":"2025-03-02T13:10:51+00:00","dateModified":"2025-03-02T13:10:52+00:00","mainEntityOfPage":{"@id":"https:\/\/wp-dk.poland.travel\/regionen-lubelskie\/"},"wordCount":266,"commentCount":0,"publisher":{"@id":"https:\/\/www.polen.travel\/dk\/#organization"},"image":{"@id":"https:\/\/wp-dk.poland.travel\/regionen-lubelskie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/02\/Roztoczanski-PN_1920.jpg","keywords":["hvad-skal-man-se","regioner"],"articleSection":["Regioner"],"inLanguage":"da-DK","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/wp-dk.poland.travel\/regionen-lubelskie\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/wp-dk.poland.travel\/regionen-lubelskie\/","url":"https:\/\/wp-dk.poland.travel\/regionen-lubelskie\/","name":"Regionen Lubelskie - Polen Travel (DK)","isPartOf":{"@id":"https:\/\/www.polen.travel\/dk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wp-dk.poland.travel\/regionen-lubelskie\/#primaryimage"},"image":{"@id":"https:\/\/wp-dk.poland.travel\/regionen-lubelskie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/02\/Roztoczanski-PN_1920.jpg","datePublished":"2025-03-02T13:10:51+00:00","dateModified":"2025-03-02T13:10:52+00:00","breadcrumb":{"@id":"https:\/\/wp-dk.poland.travel\/regionen-lubelskie\/#breadcrumb"},"inLanguage":"da-DK","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wp-dk.poland.travel\/regionen-lubelskie\/"]}]},{"@type":"ImageObject","inLanguage":"da-DK","@id":"https:\/\/wp-dk.poland.travel\/regionen-lubelskie\/#primaryimage","url":"https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/02\/Roztoczanski-PN_1920.jpg","contentUrl":"https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/02\/Roztoczanski-PN_1920.jpg","width":1920,"height":582,"caption":"Horses , Stawy Echo , Roztocze National Park , Poland"},{"@type":"BreadcrumbList","@id":"https:\/\/wp-dk.poland.travel\/regionen-lubelskie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home page","item":"https:\/\/www.polen.travel\/dk\/"},{"@type":"ListItem","position":2,"name":"Oplev Polen","item":"https:\/\/wp-dk.poland.travel\/oplev-polen\/"},{"@type":"ListItem","position":3,"name":"Regioner","item":"https:\/\/wp-dk.poland.travel\/regioner\/"},{"@type":"ListItem","position":4,"name":"Regionen Lubelskie"}]},{"@type":"WebSite","@id":"https:\/\/www.polen.travel\/dk\/#website","url":"https:\/\/www.polen.travel\/dk\/","name":"Polen Travel (DK)","description":"...","publisher":{"@id":"https:\/\/www.polen.travel\/dk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.polen.travel\/dk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"da-DK"},{"@type":"Organization","@id":"https:\/\/www.polen.travel\/dk\/#organization","name":"Polen Travel (DK)","url":"https:\/\/www.polen.travel\/dk\/","logo":{"@type":"ImageObject","inLanguage":"da-DK","@id":"https:\/\/www.polen.travel\/dk\/#\/schema\/logo\/image\/","url":"https:\/\/en-en.polska.travel\/wp-content\/uploads\/sites\/24\/2022\/11\/logo.svg","contentUrl":"https:\/\/en-en.polska.travel\/wp-content\/uploads\/sites\/24\/2022\/11\/logo.svg","width":198,"height":96,"caption":"Polen Travel (DK)"},"image":{"@id":"https:\/\/www.polen.travel\/dk\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"","url":"https:\/\/www.polen.travel\/dk\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/www.polen.travel\/dk\/wp-json\/wp\/v2\/posts\/32110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.polen.travel\/dk\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.polen.travel\/dk\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.polen.travel\/dk\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.polen.travel\/dk\/wp-json\/wp\/v2\/comments?post=32110"}],"version-history":[{"count":4,"href":"https:\/\/www.polen.travel\/dk\/wp-json\/wp\/v2\/posts\/32110\/revisions"}],"predecessor-version":[{"id":33218,"href":"https:\/\/www.polen.travel\/dk\/wp-json\/wp\/v2\/posts\/32110\/revisions\/33218"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.polen.travel\/dk\/wp-json\/wp\/v2\/media\/21110"}],"wp:attachment":[{"href":"https:\/\/www.polen.travel\/dk\/wp-json\/wp\/v2\/media?parent=32110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.polen.travel\/dk\/wp-json\/wp\/v2\/categories?post=32110"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.polen.travel\/dk\/wp-json\/wp\/v2\/tags?post=32110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}