{"id":31849,"date":"2025-03-20T20:26:15","date_gmt":"2025-03-20T19:26:15","guid":{"rendered":"https:\/\/www.polen.travel\/dk\/?p=31849"},"modified":"2025-03-20T20:26:16","modified_gmt":"2025-03-20T19:26:16","slug":"religion","status":"publish","type":"post","link":"https:\/\/www.polen.travel\/dk\/religion\/","title":{"rendered":"Religion"},"content":{"rendered":"\n<div class=\"wp-block-group is-style-container-medium\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h3 class=\"wp-block-heading\">Religion<\/h3>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-spacer-small\"><\/div>\n\n\n\n<p>Over 34 millioner katolikker, omkring 500.000 ortodokse kristne, mere end 150.000 protestanter, omkring 130.000 Jehovas Vidner og 45.000 gammelkatolikker har deres kirker i Polen. Der er ogs\u00e5 bev\u00e6gelser og trossamfund, som kun t\u00e6ller et par hundrede troende.<\/p>\n\n\n\n<p>Det religi\u00f8se liv blomstrer tusindvis af steder over hele Polen. Ortodokse j\u00f8der beder i Rehuh-Synagogen i Krakow, tatarer samles i moskeer i Bohoniki og Kruszyniany, buddhister mediterer i deres tempel i Kuchary. Wodzilki. I den lille landsby Stefkowa i Stary Potok-Dalen i Bieszczady-Bjergene finder man en gr\u00e6skkatolsk tr\u00e6kirke, en romerskkatolsk stenkirke og \u201dTatargraven\u201d \u2013 det eneste sted i Polen, hvor en tatarh\u00f8vding sandsynligvis er begravet.<\/p>\n<\/div><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-spacer-small\"><\/div>\n\n\n\n<div class=\"wp-block-group is-style-container\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">  <div class=\"gallery-tiles gallery-tiles--rows-2-3 lightgallery\">\r\n          <a href=\"https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/07\/HERITAGE_0002_16633_Krak_kosc_Mariacki_oltarz_KK_HR.jpg\" class=\"gallery-tiles__item\" data-src=\"https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/07\/HERITAGE_0002_16633_Krak_kosc_Mariacki_oltarz_KK_HR.jpg\"\r\n        aria-label=\"Otw\u00f3rz powi\u0119kszone zdj\u0119cie: HERITAGE_0002_16633_Krak_kosc_Mariacki_oltarz_KK_HR\">\r\n        <img loading=\"lazy\" decoding=\"async\" width=\"1170\" height=\"780\" src=\"https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/07\/HERITAGE_0002_16633_Krak_kosc_Mariacki_oltarz_KK_HR.jpg\" class=\"gallery-tiles__thumb\" alt=\"\" srcset=\"https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/07\/HERITAGE_0002_16633_Krak_kosc_Mariacki_oltarz_KK_HR.jpg 1170w, https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/07\/HERITAGE_0002_16633_Krak_kosc_Mariacki_oltarz_KK_HR-600x400.jpg 600w, https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/07\/HERITAGE_0002_16633_Krak_kosc_Mariacki_oltarz_KK_HR-768x512.jpg 768w\" sizes=\"auto, (max-width: 1170px) 100vw, 1170px\" \/>      <\/a>\r\n          <a href=\"https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/07\/10599_Kosciol-Jawor_WLO_HR.jpg\" class=\"gallery-tiles__item\" data-src=\"https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/07\/10599_Kosciol-Jawor_WLO_HR.jpg\"\r\n        aria-label=\"Otw\u00f3rz powi\u0119kszone zdj\u0119cie: SONY DSC\">\r\n        <img loading=\"lazy\" decoding=\"async\" width=\"1170\" height=\"757\" src=\"https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/07\/10599_Kosciol-Jawor_WLO_HR.jpg\" class=\"gallery-tiles__thumb\" alt=\"\" srcset=\"https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/07\/10599_Kosciol-Jawor_WLO_HR.jpg 1170w, https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/07\/10599_Kosciol-Jawor_WLO_HR-600x388.jpg 600w, https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/07\/10599_Kosciol-Jawor_WLO_HR-768x497.jpg 768w\" sizes=\"auto, (max-width: 1170px) 100vw, 1170px\" \/>      <\/a>\r\n          <a href=\"https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2022\/12\/bialystok_cerkiew_sw_ducha_1170.jpg\" class=\"gallery-tiles__item\" data-src=\"https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2022\/12\/bialystok_cerkiew_sw_ducha_1170.jpg\"\r\n        aria-label=\"Otw\u00f3rz powi\u0119kszone zdj\u0119cie: Cerkiew \u015bw. Ducha w Bia\u0142ymstoku\">\r\n        <img loading=\"lazy\" decoding=\"async\" width=\"1170\" height=\"780\" src=\"https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2022\/12\/bialystok_cerkiew_sw_ducha_1170.jpg\" class=\"gallery-tiles__thumb\" alt=\"Cerkiew \u015bw. Ducha w Bia\u0142ymstoku\" srcset=\"https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2022\/12\/bialystok_cerkiew_sw_ducha_1170.jpg 1170w, https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2022\/12\/bialystok_cerkiew_sw_ducha_1170-600x400.jpg 600w, https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2022\/12\/bialystok_cerkiew_sw_ducha_1170-768x512.jpg 768w\" sizes=\"auto, (max-width: 1170px) 100vw, 1170px\" \/>      <\/a>\r\n          <a href=\"https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/07\/tykocin_wielka_synagoga_1170_2.jpg\" class=\"gallery-tiles__item\" data-src=\"https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/07\/tykocin_wielka_synagoga_1170_2.jpg\"\r\n        aria-label=\"Otw\u00f3rz powi\u0119kszone zdj\u0119cie: Obiekty Skaralne\">\r\n        <img loading=\"lazy\" decoding=\"async\" width=\"1170\" height=\"780\" src=\"https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/07\/tykocin_wielka_synagoga_1170_2.jpg\" class=\"gallery-tiles__thumb\" alt=\"\" srcset=\"https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/07\/tykocin_wielka_synagoga_1170_2.jpg 1170w, https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/07\/tykocin_wielka_synagoga_1170_2-600x400.jpg 600w, https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/07\/tykocin_wielka_synagoga_1170_2-768x512.jpg 768w\" sizes=\"auto, (max-width: 1170px) 100vw, 1170px\" \/>      <\/a>\r\n          <a href=\"https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2022\/12\/meczet_w_kruszynianach.jpg\" class=\"gallery-tiles__item\" data-src=\"https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2022\/12\/meczet_w_kruszynianach.jpg\"\r\n        aria-label=\"Otw\u00f3rz powi\u0119kszone zdj\u0119cie: Meczet\">\r\n        <img loading=\"lazy\" decoding=\"async\" width=\"1170\" height=\"780\" src=\"https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2022\/12\/meczet_w_kruszynianach.jpg\" class=\"gallery-tiles__thumb\" alt=\"Meczet\" srcset=\"https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2022\/12\/meczet_w_kruszynianach.jpg 1170w, https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2022\/12\/meczet_w_kruszynianach-600x400.jpg 600w, https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2022\/12\/meczet_w_kruszynianach-768x512.jpg 768w\" sizes=\"auto, (max-width: 1170px) 100vw, 1170px\" \/>      <\/a>\r\n      <\/div>\r\n<\/div><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-spacer-small\"><\/div>\n\n\n\n<div class=\"wp-block-group has-background\" style=\"background-color:#eeeeee\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-spacer-small\"><\/div>\n\n\n\n<div class=\"wp-block-group is-style-container\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h3 class=\"wp-block-heading\">L\u00e6s flere artikler:<\/h3>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-spacer-small\"><\/div>\n\n\n<div class=\"overflow\">\n  <div class=\"post-slider swiper post-slider--small\" data-schema=\"small\">\n\n    <div class=\"swiper-wrapper\">\n              <div class=\"swiper-slide post-slide\">\n                      <a href=\"https:\/\/www.polen.travel\/dk\/kommunikation\/\" class=\"post-box post-box--small\" style=\" background-image: url(https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2025\/02\/169197674_kobieta_praca_zdalna-xl.jpeg);\">\n          <div class=\"post-box__hover\" style=\"background-image: url(https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2025\/02\/169197674_kobieta_praca_zdalna-xl.jpeg);\"><\/div>\n        <div class=\"post-box__info\">\n            <div class=\"post-box__title\">Kommunikation<\/div>\n      <div class=\"post-box__more\">Se mere<\/div>\n    <\/div>\n  <\/a>\n\n          <\/div>\n              <div class=\"swiper-slide post-slide\">\n                      <a href=\"https:\/\/www.polen.travel\/dk\/valuta\/\" class=\"post-box post-box--small\" style=\" background-image: url(https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/07\/253627521-600x401.jpg);\">\n          <div class=\"post-box__hover\" style=\"background-image: url(https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/11\/425277450_Polskie_banknoty-xl-600x400.jpg);\"><\/div>\n        <div class=\"post-box__info\">\n            <div class=\"post-box__title\">Valuta<\/div>\n      <div class=\"post-box__more\">Se mere<\/div>\n    <\/div>\n  <\/a>\n\n          <\/div>\n              <div class=\"swiper-slide post-slide\">\n                      <a href=\"https:\/\/www.polen.travel\/dk\/i-nodsituationer\/\" class=\"post-box post-box--small\" style=\" background-image: url(https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2025\/03\/call-center540.jpg);\">\n          <div class=\"post-box__hover\" style=\"background-image: url(https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2025\/03\/call-center540.jpg);\"><\/div>\n        <div class=\"post-box__info\">\n            <div class=\"post-box__title\">I N\u00f8dsituationer<\/div>\n      <div class=\"post-box__more\">Se mere<\/div>\n    <\/div>\n  <\/a>\n\n          <\/div>\n              <div class=\"swiper-slide post-slide\">\n                      <a href=\"https:\/\/www.polen.travel\/dk\/hoteller-og-restauranter\/\" class=\"post-box post-box--small\" style=\" background-image: url(https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/07\/Podroz_GettyImages-600x577.jpg);\">\n          <div class=\"post-box__hover\" style=\"background-image: url(https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/08\/Walizka_GettyImages-505640207-600x400.jpg);\"><\/div>\n        <div class=\"post-box__info\">\n            <div class=\"post-box__title\">Hoteller og restauranter<\/div>\n      <div class=\"post-box__more\">Se mere<\/div>\n    <\/div>\n  <\/a>\n\n          <\/div>\n              <div class=\"swiper-slide post-slide\">\n                      <a href=\"https:\/\/www.polen.travel\/dk\/love-og-regler\/\" class=\"post-box post-box--small\" style=\" background-image: url(https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/11\/Przepisy-prawne_540_360.jpg);\">\n          <div class=\"post-box__hover\" style=\"background-image: url(https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/11\/Przepisy-prawne_540_360.jpg);\"><\/div>\n        <div class=\"post-box__info\">\n            <div class=\"post-box__title\">Love og regler<\/div>\n      <div class=\"post-box__more\">Se mere<\/div>\n    <\/div>\n  <\/a>\n\n          <\/div>\n              <div class=\"swiper-slide post-slide\">\n                      <a href=\"https:\/\/www.polen.travel\/dk\/den-polske-karakter\/\" class=\"post-box post-box--small\" style=\" background-image: url(https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/07\/329545613_Krakow_Adobe-600x400.jpg);\">\n          <div class=\"post-box__hover\" style=\"background-image: url(https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/07\/6_Warszawa_syrenka_warszawska_MH-HD-1-400x600.jpg);\"><\/div>\n        <div class=\"post-box__info\">\n            <div class=\"post-box__title\">Den polske karakter<\/div>\n      <div class=\"post-box__more\">Se mere<\/div>\n    <\/div>\n  <\/a>\n\n          <\/div>\n              <div class=\"swiper-slide post-slide\">\n                      <a href=\"https:\/\/www.polen.travel\/dk\/turisme-faerdselstavler\/\" class=\"post-box post-box--small\" style=\" background-image: url(https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/05\/am_aktywniwpodrozy-wizerunek.jpg);\">\n          <div class=\"post-box__hover\" style=\"background-image: url(https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/07\/Podroz_GettyImages-600x577.jpg);\"><\/div>\n        <div class=\"post-box__info\">\n            <div class=\"post-box__title\">Turisme F\u00e6rdselstavler<\/div>\n      <div class=\"post-box__more\">Se mere<\/div>\n    <\/div>\n  <\/a>\n\n          <\/div>\n              <div class=\"swiper-slide post-slide\">\n                      <a href=\"https:\/\/www.polen.travel\/dk\/shopping\/\" class=\"post-box post-box--small\" style=\" background-image: url(https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2025\/02\/sukien.jpg);\">\n          <div class=\"post-box__hover\" style=\"background-image: url(https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2025\/02\/gucci.jpg);\"><\/div>\n        <div class=\"post-box__info\">\n            <div class=\"post-box__title\">Shopping<\/div>\n      <div class=\"post-box__more\">Se mere<\/div>\n    <\/div>\n  <\/a>\n\n          <\/div>\n              <div class=\"swiper-slide post-slide\">\n                      <a href=\"https:\/\/www.polen.travel\/dk\/folklore\/\" class=\"post-box post-box--small\" style=\" background-image: url(https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/01\/68758763_Fotolia_Stroj_regionalny_HR-399x600.jpg);\">\n          <div class=\"post-box__hover\" style=\"background-image: url(https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/07\/00152_2550_Wielkanoc_dekoracje_KK_HR-600x349.jpg);\"><\/div>\n        <div class=\"post-box__info\">\n            <div class=\"post-box__title\">Folklore<\/div>\n      <div class=\"post-box__more\">Se mere<\/div>\n    <\/div>\n  <\/a>\n\n          <\/div>\n              <div class=\"swiper-slide post-slide\">\n                      <a href=\"https:\/\/www.polen.travel\/dk\/religion\/\" class=\"post-box post-box--small\" style=\" background-image: url(https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2023\/07\/HERITAGE_0002_16633_Krak_kosc_Mariacki_oltarz_KK_HR-600x400.jpg);\">\n          <div class=\"post-box__hover\" style=\"background-image: url(https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2022\/12\/kozy_kosciol_apostolow_szymona_i_tadeusza_judy_540.jpg);\"><\/div>\n        <div class=\"post-box__info\">\n            <div class=\"post-box__title\">Religion<\/div>\n      <div class=\"post-box__more\">Se mere<\/div>\n    <\/div>\n  <\/a>\n\n          <\/div>\n              <div class=\"swiper-slide post-slide\">\n                      <a href=\"https:\/\/www.polen.travel\/dk\/vejskilte-for-turister\/\" class=\"post-box post-box--small\" style=\" background-image: url(https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2025\/03\/235842874_austostrada-xl.jpeg);\">\n          <div class=\"post-box__hover\" style=\"background-image: url(https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2025\/03\/235842874_austostrada-xl.jpeg);\"><\/div>\n        <div class=\"post-box__info\">\n            <div class=\"post-box__title\">Vejskilte for Turister<\/div>\n      <div class=\"post-box__more\">Se mere<\/div>\n    <\/div>\n  <\/a>\n\n          <\/div>\n          <\/div>\n    <div class=\"post-slider__pagination\"><\/div>\n  <\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-spacer-small\"><\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Religion Over 34 millioner katolikker, omkring 500.000 ortodokse kristne, mere end 150.000 protestanter, omkring 130.000 Jehovas Vidner og 45.000 gammelkatolikker har deres kirker i Polen. Der er ogs\u00e5 bev\u00e6gelser og trossamfund, som kun t\u00e6ller et par hundrede troende. Det religi\u00f8se liv blomstrer tusindvis af steder over hele Polen. Ortodokse j\u00f8der beder i Rehuh-Synagogen i Krakow, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":30914,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1050],"tags":[1198,1200],"class_list":["post-31849","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-praktisk-information","tag-om-polen","tag-nyttige-informationer"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Religion - Polen Travel (DK)<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wp-dk.poland.travel\/religion\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Religion - Polen Travel (DK)\" \/>\n<meta property=\"og:description\" content=\"Religion Over 34 millioner katolikker, omkring 500.000 ortodokse kristne, mere end 150.000 protestanter, omkring 130.000 Jehovas Vidner og 45.000 gammelkatolikker har deres kirker i Polen. Der er ogs\u00e5 bev\u00e6gelser og trossamfund, som kun t\u00e6ller et par hundrede troende. Det religi\u00f8se liv blomstrer tusindvis af steder over hele Polen. Ortodokse j\u00f8der beder i Rehuh-Synagogen i Krakow, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wp-dk.poland.travel\/religion\/\" \/>\n<meta property=\"og:site_name\" content=\"Polen Travel (DK)\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-20T19:26:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-20T19:26:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wp-dk.poland.travel\/wp-content\/uploads\/sites\/24\/2024\/03\/debno_drewniane_koscioly_poludniowej_malopolski_1170x300.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Napisane przez\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Szacowany czas czytania\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuta\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/wp-dk.poland.travel\\\/religion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wp-dk.poland.travel\\\/religion\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Religion\",\"datePublished\":\"2025-03-20T19:26:15+00:00\",\"dateModified\":\"2025-03-20T19:26:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/wp-dk.poland.travel\\\/religion\\\/\"},\"wordCount\":109,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.polen.travel\\\/dk\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/wp-dk.poland.travel\\\/religion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.polen.travel\\\/dk\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2024\\\/03\\\/debno_drewniane_koscioly_poludniowej_malopolski_1170x300.jpg\",\"keywords\":[\"om-polen\",\"nyttige-informationer\"],\"articleSection\":[\"Praktisk information\"],\"inLanguage\":\"pl-PL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wp-dk.poland.travel\\\/religion\\\/\",\"url\":\"https:\\\/\\\/wp-dk.poland.travel\\\/religion\\\/\",\"name\":\"Religion - Polen Travel (DK)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.polen.travel\\\/dk\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wp-dk.poland.travel\\\/religion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wp-dk.poland.travel\\\/religion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.polen.travel\\\/dk\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2024\\\/03\\\/debno_drewniane_koscioly_poludniowej_malopolski_1170x300.jpg\",\"datePublished\":\"2025-03-20T19:26:15+00:00\",\"dateModified\":\"2025-03-20T19:26:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wp-dk.poland.travel\\\/religion\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wp-dk.poland.travel\\\/religion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/wp-dk.poland.travel\\\/religion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.polen.travel\\\/dk\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2024\\\/03\\\/debno_drewniane_koscioly_poludniowej_malopolski_1170x300.jpg\",\"contentUrl\":\"https:\\\/\\\/www.polen.travel\\\/dk\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2024\\\/03\\\/debno_drewniane_koscioly_poludniowej_malopolski_1170x300.jpg\",\"width\":1170,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wp-dk.poland.travel\\\/religion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home page\",\"item\":\"https:\\\/\\\/www.polen.travel\\\/dk\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Praktisk information\",\"item\":\"https:\\\/\\\/wp-dk.poland.travel\\\/praktisk-information\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Religion\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.polen.travel\\\/dk\\\/#website\",\"url\":\"https:\\\/\\\/www.polen.travel\\\/dk\\\/\",\"name\":\"Polen Travel (DK)\",\"description\":\"...\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.polen.travel\\\/dk\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.polen.travel\\\/dk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.polen.travel\\\/dk\\\/#organization\",\"name\":\"Polen Travel (DK)\",\"url\":\"https:\\\/\\\/www.polen.travel\\\/dk\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/www.polen.travel\\\/dk\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/en-en.polska.travel\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2022\\\/11\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/en-en.polska.travel\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2022\\\/11\\\/logo.svg\",\"width\":198,\"height\":96,\"caption\":\"Polen Travel (DK)\"},\"image\":{\"@id\":\"https:\\\/\\\/www.polen.travel\\\/dk\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\\\/\\\/www.polen.travel\\\/dk\\\/author\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Religion - Polen Travel (DK)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wp-dk.poland.travel\/religion\/","og_locale":"pl_PL","og_type":"article","og_title":"Religion - Polen Travel (DK)","og_description":"Religion Over 34 millioner katolikker, omkring 500.000 ortodokse kristne, mere end 150.000 protestanter, omkring 130.000 Jehovas Vidner og 45.000 gammelkatolikker har deres kirker i Polen. Der er ogs\u00e5 bev\u00e6gelser og trossamfund, som kun t\u00e6ller et par hundrede troende. Det religi\u00f8se liv blomstrer tusindvis af steder over hele Polen. Ortodokse j\u00f8der beder i Rehuh-Synagogen i Krakow, [&hellip;]","og_url":"https:\/\/wp-dk.poland.travel\/religion\/","og_site_name":"Polen Travel (DK)","article_published_time":"2025-03-20T19:26:15+00:00","article_modified_time":"2025-03-20T19:26:16+00:00","og_image":[{"width":1170,"height":300,"url":"https:\/\/wp-dk.poland.travel\/wp-content\/uploads\/sites\/24\/2024\/03\/debno_drewniane_koscioly_poludniowej_malopolski_1170x300.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Napisane przez":"","Szacowany czas czytania":"1 minuta"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/wp-dk.poland.travel\/religion\/#article","isPartOf":{"@id":"https:\/\/wp-dk.poland.travel\/religion\/"},"author":{"name":"","@id":""},"headline":"Religion","datePublished":"2025-03-20T19:26:15+00:00","dateModified":"2025-03-20T19:26:16+00:00","mainEntityOfPage":{"@id":"https:\/\/wp-dk.poland.travel\/religion\/"},"wordCount":109,"commentCount":0,"publisher":{"@id":"https:\/\/www.polen.travel\/dk\/#organization"},"image":{"@id":"https:\/\/wp-dk.poland.travel\/religion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2024\/03\/debno_drewniane_koscioly_poludniowej_malopolski_1170x300.jpg","keywords":["om-polen","nyttige-informationer"],"articleSection":["Praktisk information"],"inLanguage":"pl-PL"},{"@type":"WebPage","@id":"https:\/\/wp-dk.poland.travel\/religion\/","url":"https:\/\/wp-dk.poland.travel\/religion\/","name":"Religion - Polen Travel (DK)","isPartOf":{"@id":"https:\/\/www.polen.travel\/dk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wp-dk.poland.travel\/religion\/#primaryimage"},"image":{"@id":"https:\/\/wp-dk.poland.travel\/religion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2024\/03\/debno_drewniane_koscioly_poludniowej_malopolski_1170x300.jpg","datePublished":"2025-03-20T19:26:15+00:00","dateModified":"2025-03-20T19:26:16+00:00","breadcrumb":{"@id":"https:\/\/wp-dk.poland.travel\/religion\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wp-dk.poland.travel\/religion\/"]}]},{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/wp-dk.poland.travel\/religion\/#primaryimage","url":"https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2024\/03\/debno_drewniane_koscioly_poludniowej_malopolski_1170x300.jpg","contentUrl":"https:\/\/www.polen.travel\/dk\/wp-content\/uploads\/sites\/24\/2024\/03\/debno_drewniane_koscioly_poludniowej_malopolski_1170x300.jpg","width":1170,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/wp-dk.poland.travel\/religion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home page","item":"https:\/\/www.polen.travel\/dk\/"},{"@type":"ListItem","position":2,"name":"Praktisk information","item":"https:\/\/wp-dk.poland.travel\/praktisk-information\/"},{"@type":"ListItem","position":3,"name":"Religion"}]},{"@type":"WebSite","@id":"https:\/\/www.polen.travel\/dk\/#website","url":"https:\/\/www.polen.travel\/dk\/","name":"Polen Travel (DK)","description":"...","publisher":{"@id":"https:\/\/www.polen.travel\/dk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.polen.travel\/dk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":"Organization","@id":"https:\/\/www.polen.travel\/dk\/#organization","name":"Polen Travel (DK)","url":"https:\/\/www.polen.travel\/dk\/","logo":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/www.polen.travel\/dk\/#\/schema\/logo\/image\/","url":"https:\/\/en-en.polska.travel\/wp-content\/uploads\/sites\/24\/2022\/11\/logo.svg","contentUrl":"https:\/\/en-en.polska.travel\/wp-content\/uploads\/sites\/24\/2022\/11\/logo.svg","width":198,"height":96,"caption":"Polen Travel (DK)"},"image":{"@id":"https:\/\/www.polen.travel\/dk\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"","url":"https:\/\/www.polen.travel\/dk\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/www.polen.travel\/dk\/wp-json\/wp\/v2\/posts\/31849","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.polen.travel\/dk\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.polen.travel\/dk\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.polen.travel\/dk\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.polen.travel\/dk\/wp-json\/wp\/v2\/comments?post=31849"}],"version-history":[{"count":4,"href":"https:\/\/www.polen.travel\/dk\/wp-json\/wp\/v2\/posts\/31849\/revisions"}],"predecessor-version":[{"id":33553,"href":"https:\/\/www.polen.travel\/dk\/wp-json\/wp\/v2\/posts\/31849\/revisions\/33553"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.polen.travel\/dk\/wp-json\/wp\/v2\/media\/30914"}],"wp:attachment":[{"href":"https:\/\/www.polen.travel\/dk\/wp-json\/wp\/v2\/media?parent=31849"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.polen.travel\/dk\/wp-json\/wp\/v2\/categories?post=31849"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.polen.travel\/dk\/wp-json\/wp\/v2\/tags?post=31849"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}