{"id":20217,"date":"2023-02-09T13:36:42","date_gmt":"2023-02-09T12:36:42","guid":{"rendered":"https:\/\/en-en.polska.travel\/?page_id=20217"},"modified":"2025-03-26T14:25:24","modified_gmt":"2025-03-26T13:25:24","slug":"news","status":"publish","type":"page","link":"https:\/\/www.polen.travel\/de\/news\/","title":{"rendered":"News"},"content":{"rendered":"\n<div class=\"wp-block-group is-style-container\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading is-style-heading-48\">News<\/h2>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<p><\/p>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-spacer-small\"><\/div>\n\n\n\n<div class=\"wp-block-group is-style-container\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n  <div class=\"links-tiles links-tiles--rows-2-3\" id=\"listing\">\n            <div class=\"links-tiles__item\">\n                      <a href=\"https:\/\/www.polen.travel\/de\/tatry-super-ski\/\" class=\"link-box\" style=\" background-image: url(https:\/\/www.polen.travel\/de\/wp-content\/uploads\/sites\/8\/2022\/12\/PKL_kasprowy_wierch_1170.jpg);\">\n              <div class=\"link-box__hover\" style=\"background-image: url(https:\/\/www.polen.travel\/de\/wp-content\/uploads\/sites\/8\/2025\/01\/kasprowy_wierch_narty-600x400-1.jpg);\"><\/div>\n        <div class=\"link-box__info\">\n      <div class=\"link-box__title\">Tatry Super Ski mit Polens h\u00f6chsten Skipisten<\/div>\n      <div class=\"link-box__more\">Mehr sehen<\/div>\n    <\/div>\n  <\/a>\n\n          <\/div>\n                  <div class=\"links-tiles__item\">\n                      <a href=\"https:\/\/www.polen.travel\/de\/unesco-weltgeopark-land-der-erloschenen-vulkane\/\" class=\"link-box\" style=\" background-image: url(https:\/\/www.polen.travel\/de\/wp-content\/uploads\/sites\/8\/2025\/12\/Gory_Kaczawskie_-_Kraina_wygaslych_wulkanow-1200x800.jpg);\">\n              <div class=\"link-box__hover\" style=\"background-image: url(https:\/\/www.polen.travel\/de\/wp-content\/uploads\/sites\/8\/2025\/12\/org_MJOJG.jpg);\"><\/div>\n        <div class=\"link-box__info\">\n      <div class=\"link-box__title\">UNESCO-Weltgeopark &#8211; Land der erloschenen Vulkane<\/div>\n      <div class=\"link-box__more\">Mehr sehen<\/div>\n    <\/div>\n  <\/a>\n\n          <\/div>\n                  <div class=\"links-tiles__item\">\n                      <a href=\"https:\/\/www.polen.travel\/de\/1000-jahre-konigskronung\/\" class=\"link-box\" style=\" background-image: url(https:\/\/www.polen.travel\/de\/wp-content\/uploads\/sites\/8\/2025\/04\/465889831_521131110794708_1550280448557028927_n-2.jpg);\">\n              <div class=\"link-box__hover\" style=\"background-image: url(https:\/\/www.polen.travel\/de\/wp-content\/uploads\/sites\/8\/2022\/12\/poznan_most_jordana_i_katedra_1170.jpg);\"><\/div>\n        <div class=\"link-box__info\">\n      <div class=\"link-box__title\">1000 Jahre K\u00f6nigskr\u00f6nung<\/div>\n      <div class=\"link-box__more\">Mehr sehen<\/div>\n    <\/div>\n  <\/a>\n\n          <\/div>\n                  <div class=\"links-tiles__item\">\n                      <a href=\"https:\/\/www.polen.travel\/de\/mit-volldampf-in-den-fruhling-in-wolsztyn\/\" class=\"link-box\" style=\" background-image: url(https:\/\/www.polen.travel\/de\/wp-content\/uploads\/sites\/8\/2025\/04\/Parowoz-Fot.-Adam-Brombor.jpg);\">\n              <div class=\"link-box__hover\" style=\"background-image: url(https:\/\/www.polen.travel\/de\/wp-content\/uploads\/sites\/8\/2025\/04\/fot.-Wojciech-Lis-1.jpg);\"><\/div>\n        <div class=\"link-box__info\">\n      <div class=\"link-box__title\">Mit Volldampf in den Fr\u00fchling in Wolsztyn<\/div>\n      <div class=\"link-box__more\">Mehr sehen<\/div>\n    <\/div>\n  <\/a>\n\n          <\/div>\n                  <div class=\"links-tiles__item\">\n                      <a href=\"https:\/\/www.polen.travel\/de\/gdansk-hat-schonsten-weihnachtsmarkt-europas\/\" class=\"link-box\" style=\" background-image: url(https:\/\/www.polen.travel\/de\/wp-content\/uploads\/sites\/8\/2024\/11\/g1-1200x741.jpg);\">\n              <div class=\"link-box__hover\" style=\"background-image: url(https:\/\/www.polen.travel\/de\/wp-content\/uploads\/sites\/8\/2024\/11\/g2-1200x799.jpg);\"><\/div>\n        <div class=\"link-box__info\">\n      <div class=\"link-box__title\">Gda\u0144sk hat sch\u00f6nsten Weihnachtsmarkt Europas<\/div>\n      <div class=\"link-box__more\">Mehr sehen<\/div>\n    <\/div>\n  <\/a>\n\n          <\/div>\n                  <div class=\"links-tiles__item\">\n                      <a href=\"https:\/\/www.polen.travel\/de\/die-app-route-der-gotischen-burgen-sofort-als-download-fur-android-und-ios-erhaltlich\/\" class=\"link-box\" style=\" background-image: url(https:\/\/www.polen.travel\/de\/wp-content\/uploads\/sites\/8\/2022\/12\/olsztyn_zamek_3_1170.jpg);\">\n              <div class=\"link-box__hover\" style=\"background-image: url(https:\/\/www.polen.travel\/de\/wp-content\/uploads\/sites\/8\/2023\/05\/lidzbark.jpg);\"><\/div>\n        <div class=\"link-box__info\">\n      <div class=\"link-box__title\">Die App &quot;Route der gotischen Burgen&quot; &#8211; sofort als Download f\u00fcr Android und iOS erh\u00e4ltlich<\/div>\n      <div class=\"link-box__more\">Mehr sehen<\/div>\n    <\/div>\n  <\/a>\n\n          <\/div>\n                  <div class=\"links-tiles__item\">\n                      <a href=\"https:\/\/www.polen.travel\/de\/auf-den-spuren-von-fryderyk-chopin-in-polen\/\" class=\"link-box\" style=\" background-image: url(https:\/\/www.polen.travel\/de\/wp-content\/uploads\/sites\/8\/2022\/12\/lazienki_warszawskie_1170.jpg);\">\n              <div class=\"link-box__hover\" style=\"background-image: url(https:\/\/www.polen.travel\/de\/wp-content\/uploads\/sites\/8\/2022\/12\/zelazowa_wola_dworek_jesien_1170.jpeg);\"><\/div>\n        <div class=\"link-box__info\">\n      <div class=\"link-box__title\">Auf den Spuren von Fryderyk Chopin in Polen<\/div>\n      <div class=\"link-box__more\">Mehr sehen<\/div>\n    <\/div>\n  <\/a>\n\n          <\/div>\n                  <div class=\"links-tiles__item\">\n                      <a href=\"https:\/\/www.polen.travel\/de\/neue-sky-bar-auf-warschauer-nyx\/\" class=\"link-box\" style=\" background-image: url(https:\/\/www.polen.travel\/de\/wp-content\/uploads\/sites\/8\/2023\/10\/2022.07.05_nyx3-1200x799.jpg);\">\n              <div class=\"link-box__hover\" style=\"background-image: url(https:\/\/www.polen.travel\/de\/wp-content\/uploads\/sites\/8\/2023\/10\/2022.07.05_nyx2-1200x798.jpg);\"><\/div>\n        <div class=\"link-box__info\">\n      <div class=\"link-box__title\">Neue Sky-Bar auf Warschauer NYX<\/div>\n      <div class=\"link-box__more\">Mehr sehen<\/div>\n    <\/div>\n  <\/a>\n\n          <\/div>\n                  <div class=\"links-tiles__item\">\n                      <a href=\"https:\/\/www.polen.travel\/de\/der-neue-reisefuhrer-uber-nordpolen\/\" class=\"link-box\" style=\" background-image: url(https:\/\/www.polen.travel\/de\/wp-content\/uploads\/sites\/8\/2023\/07\/Gdansk-Motlawa.jpg);\">\n              <div class=\"link-box__hover\" style=\"background-image: url(https:\/\/www.polen.travel\/de\/wp-content\/uploads\/sites\/8\/2023\/07\/narwianski_park_narodowy_1170.jpg);\"><\/div>\n        <div class=\"link-box__info\">\n      <div class=\"link-box__title\">Der neue Reisef\u00fchrer \u00fcber Nordpolen<\/div>\n      <div class=\"link-box__more\">Mehr sehen<\/div>\n    <\/div>\n  <\/a>\n\n          <\/div>\n                  <div class=\"links-tiles__item\">\n                      <a href=\"https:\/\/www.polen.travel\/de\/freie-fahrt-vom-frischen-haff-zur-ostsee\/\" class=\"link-box\" style=\" background-image: url(https:\/\/www.polen.travel\/de\/wp-content\/uploads\/sites\/8\/2023\/10\/2022.09.17_kanal2-1200x797.jpg);\">\n              <div class=\"link-box__hover\" style=\"background-image: url(https:\/\/www.polen.travel\/de\/wp-content\/uploads\/sites\/8\/2023\/10\/2022.09.17_kanal3-1200x798.jpg);\"><\/div>\n        <div class=\"link-box__info\">\n      <div class=\"link-box__title\">Freie Fahrt vom Frischen Haff zur Ostsee<\/div>\n      <div class=\"link-box__more\">Mehr sehen<\/div>\n    <\/div>\n  <\/a>\n\n          <\/div>\n                  <div class=\"links-tiles__item\">\n                      <a href=\"https:\/\/www.polen.travel\/de\/warschau-ist-europas-beste-destination\/\" class=\"link-box\" style=\" background-image: url(https:\/\/www.polen.travel\/de\/wp-content\/uploads\/sites\/8\/2023\/07\/warszawa_lazienki_kwiaty_1170.jpg);\">\n              <div class=\"link-box__hover\" style=\"background-image: url(https:\/\/www.polen.travel\/de\/wp-content\/uploads\/sites\/8\/2022\/12\/warszawa_zamek_krolewski_slonce_1170-2.jpg);\"><\/div>\n        <div class=\"link-box__info\">\n      <div class=\"link-box__title\">Warschau ist Europas beste Destination<\/div>\n      <div class=\"link-box__more\">Mehr sehen<\/div>\n    <\/div>\n  <\/a>\n\n          <\/div>\n                  <div class=\"links-tiles__item\">\n                      <a href=\"https:\/\/www.polen.travel\/de\/tourismus-in-polen-auf-niveau-vor-corona\/\" class=\"link-box\" style=\" background-image: url(https:\/\/www.polen.travel\/de\/wp-content\/uploads\/sites\/8\/2023\/01\/POT-15.jpg);\">\n              <div class=\"link-box__hover\" style=\"background-image: url(https:\/\/www.polen.travel\/de\/wp-content\/uploads\/sites\/8\/2023\/07\/bulwary_wislane_warszawa_1170.jpg);\"><\/div>\n        <div class=\"link-box__info\">\n      <div class=\"link-box__title\">Tourismus in Polen auf Niveau vor Corona<\/div>\n      <div class=\"link-box__more\">Mehr sehen<\/div>\n    <\/div>\n  <\/a>\n\n          <\/div>\n                  <div class=\"links-tiles__item\">\n                      <a href=\"https:\/\/www.polen.travel\/de\/polen-guide-fur-feinschmecker\/\" class=\"link-box\" style=\" background-image: url(https:\/\/www.polen.travel\/de\/wp-content\/uploads\/sites\/8\/2023\/07\/01_23_0685_MICHELIN_Krakow_1200x1200-1.jpg);\">\n              <div class=\"link-box__hover\" style=\"background-image: url(https:\/\/www.polen.travel\/de\/wp-content\/uploads\/sites\/8\/2023\/07\/01_23_0685_MICHELIN_Poznan_1200x1200.jpg);\"><\/div>\n        <div class=\"link-box__info\">\n      <div class=\"link-box__title\">Polen-Guide f\u00fcr Feinschmecker<\/div>\n      <div class=\"link-box__more\">Mehr sehen<\/div>\n    <\/div>\n  <\/a>\n\n          <\/div>\n                  <div class=\"links-tiles__item\">\n                      <a href=\"https:\/\/www.polen.travel\/de\/in-der-heimat-der-pfifferlinge\/\" class=\"link-box\" style=\" background-image: url(https:\/\/www.polen.travel\/de\/wp-content\/uploads\/sites\/8\/2023\/09\/44_Fotolia_kulinarne_Grzyby_HR-Custom.jpg);\">\n              <div class=\"link-box__hover\" style=\"background-image: url(https:\/\/www.polen.travel\/de\/wp-content\/uploads\/sites\/8\/2023\/10\/83035137_Fotolia_Kurki_Grzyby_HR-1200x862.jpg);\"><\/div>\n        <div class=\"link-box__info\">\n      <div class=\"link-box__title\">In der heimat der Pfifferlinge<\/div>\n      <div class=\"link-box__more\">Mehr sehen<\/div>\n    <\/div>\n  <\/a>\n\n          <\/div>\n            <\/div>\n  \n<\/div><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group is-style-container\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<p><\/p>\n<\/div><\/div>\n\n\n\n<div style=\"height:80px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>News<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-20217","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>News - Polen Travel (DE)<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.polen.travel\/de\/news\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"News - Polen Travel (DE)\" \/>\n<meta property=\"og:description\" content=\"News\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.polen.travel\/de\/news\/\" \/>\n<meta property=\"og:site_name\" content=\"Polen Travel (DE)\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-26T13:25:24+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Szacowany czas czytania\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuta\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.polen.travel\\\/de\\\/news\\\/\",\"url\":\"https:\\\/\\\/www.polen.travel\\\/de\\\/news\\\/\",\"name\":\"News - Polen Travel (DE)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.polen.travel\\\/de\\\/#website\"},\"datePublished\":\"2023-02-09T12:36:42+00:00\",\"dateModified\":\"2025-03-26T13:25:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.polen.travel\\\/de\\\/news\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.polen.travel\\\/de\\\/news\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.polen.travel\\\/de\\\/news\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\\\/\\\/www.polen.travel\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.polen.travel\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.polen.travel\\\/de\\\/\",\"name\":\"Polen Travel (DE)\",\"description\":\"...\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.polen.travel\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.polen.travel\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.polen.travel\\\/de\\\/#organization\",\"name\":\"Polen Travel (DE)\",\"url\":\"https:\\\/\\\/www.polen.travel\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/www.polen.travel\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.polen.travel\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2022\\\/11\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.polen.travel\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2022\\\/11\\\/logo.svg\",\"width\":198,\"height\":96,\"caption\":\"Polen Travel (DE)\"},\"image\":{\"@id\":\"https:\\\/\\\/www.polen.travel\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"News - Polen Travel (DE)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.polen.travel\/de\/news\/","og_locale":"pl_PL","og_type":"article","og_title":"News - Polen Travel (DE)","og_description":"News","og_url":"https:\/\/www.polen.travel\/de\/news\/","og_site_name":"Polen Travel (DE)","article_modified_time":"2025-03-26T13:25:24+00:00","twitter_card":"summary_large_image","twitter_misc":{"Szacowany czas czytania":"1 minuta"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.polen.travel\/de\/news\/","url":"https:\/\/www.polen.travel\/de\/news\/","name":"News - Polen Travel (DE)","isPartOf":{"@id":"https:\/\/www.polen.travel\/de\/#website"},"datePublished":"2023-02-09T12:36:42+00:00","dateModified":"2025-03-26T13:25:24+00:00","breadcrumb":{"@id":"https:\/\/www.polen.travel\/de\/news\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.polen.travel\/de\/news\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.polen.travel\/de\/news\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/www.polen.travel\/de\/"},{"@type":"ListItem","position":2,"name":"News"}]},{"@type":"WebSite","@id":"https:\/\/www.polen.travel\/de\/#website","url":"https:\/\/www.polen.travel\/de\/","name":"Polen Travel (DE)","description":"...","publisher":{"@id":"https:\/\/www.polen.travel\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.polen.travel\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"},{"@type":"Organization","@id":"https:\/\/www.polen.travel\/de\/#organization","name":"Polen Travel (DE)","url":"https:\/\/www.polen.travel\/de\/","logo":{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/www.polen.travel\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.polen.travel\/de\/wp-content\/uploads\/sites\/8\/2022\/11\/logo.svg","contentUrl":"https:\/\/www.polen.travel\/de\/wp-content\/uploads\/sites\/8\/2022\/11\/logo.svg","width":198,"height":96,"caption":"Polen Travel (DE)"},"image":{"@id":"https:\/\/www.polen.travel\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.polen.travel\/de\/wp-json\/wp\/v2\/pages\/20217","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.polen.travel\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.polen.travel\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.polen.travel\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.polen.travel\/de\/wp-json\/wp\/v2\/comments?post=20217"}],"version-history":[{"count":58,"href":"https:\/\/www.polen.travel\/de\/wp-json\/wp\/v2\/pages\/20217\/revisions"}],"predecessor-version":[{"id":34326,"href":"https:\/\/www.polen.travel\/de\/wp-json\/wp\/v2\/pages\/20217\/revisions\/34326"}],"wp:attachment":[{"href":"https:\/\/www.polen.travel\/de\/wp-json\/wp\/v2\/media?parent=20217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}